{"id":313,"date":"2017-02-10T20:17:56","date_gmt":"2017-02-10T19:17:56","guid":{"rendered":"http:\/\/blogs.laverdad.es\/elalmirez\/?p=313"},"modified":"2017-02-10T20:17:56","modified_gmt":"2017-02-10T19:17:56","slug":"la-talla-del-cliente","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/elalmirez\/2017\/02\/10\/la-talla-del-cliente\/","title":{"rendered":"La talla del cliente"},"content":{"rendered":"<p>Si hablamos del sector tur\u00edstico (alojamiento y restauraci\u00f3n, fundamentalmente), \u00bfqu\u00e9 es la calidad? A esta pregunta (y a un carro de ellas m\u00e1s) contest\u00f3 esta semana Domenec Biosca, considerado por los profesionales del sector tur\u00edstico como el mejor experto de gesti\u00f3n y calidad hotelera y tur\u00edstica, asesor de decenas de empresas, algunas entre las grandes de Espa\u00f1a. y autor de numerosos t\u00edtulos sobre el tema. Biosca imparti\u00f3 una maratoniana jornada de cuatro horas en el Centro de Cualificaci\u00f3n Tur\u00edstica de Murcia, en la primera sesi\u00f3n del ciclo \u2018Re-volucionando el turismo\u2019. \u201cLa calidad es la talla del cliente\u201d, contest\u00f3. Es decir, el servicio al cliente debe ser personalizado, flexible, cambiante seg\u00fan sus necesidades, ajustado a sus caracter\u00edsticas como un buen traje. Y eso solo es posible desde empresas que rompan el viejo concepto de organizaci\u00f3n basado en departamentos, aut\u00e9nticos compartimentos estancos que se comunican entre s\u00ed mediante la burocracia y unos procedimientos de trabajo r\u00edgidos e inalterables.\u00a0 Para Biosca, en un hotel, en un restaurante, en un resort, deba haber equipos y puntos de venta. Equipos intercambiables, permeables a los otros equipos y, sobre todo, sensibles a las necesidades del cliente. El ejemplo del minibar es muy gr\u00e1fico. Si una persona se aloja de manera frecuente en un mismo hotel y siempre consume del minibar agua mineral y coca colas, por ejemplo, \u00bfpor qu\u00e9 siempre, cuando vuelve al hotel, se encuentra con el minibar lleno de bebidas alcoh\u00f3licas? Porque la gesti\u00f3n del minibar est\u00e1 protocolarizada, estandarizada y es inmutable.<\/p>\n<div id=\"attachment_315\" style=\"width: 235px\" class=\"wp-caption alignleft\"><a href=\"\/elalmirez\/wp-content\/uploads\/sites\/38\/2017\/02\/IMG_4481.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-315\" class=\"size-medium wp-image-315\" title=\"IMG_4481\" src=\"\/elalmirez\/wp-content\/uploads\/sites\/38\/2017\/02\/IMG_4481.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2017\/02\/IMG_4481.jpg 2448w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2017\/02\/IMG_4481-225x300.jpg 225w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2017\/02\/IMG_4481-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><p id=\"caption-attachment-315\" class=\"wp-caption-text\">Domenec Biosca, en el CCT.<\/p><\/div>\n<p>\u00bfPor qu\u00e9, en un restaurante, donde un cliente habitual siempre pide el mismo plato pero deja sin tocar la guarnici\u00f3n, le siguen poniendo esa guarnici\u00f3n? \u00bf C\u00f3mo es posible que en un bar de un resort, con una cerveza encima de la mesa yo pida unas aceitunas y el camarero vuelva asegur\u00e1ndome que el cocinero le ha dicho que las aceitunas las tiene reservadas para las ensaladas y que no puede pon\u00e9rmelas sueltas? \u00bfPor qu\u00e9 es tan dif\u00edcil en tantos bares y restaurantes que le pongan a uno medias raciones? \u201cLa crisis consiste en llegar tarde a los cambios\u201d, tall\u00f3 en piedra Domenec Biosca. Y los cambios que se est\u00e1n produciendo en el mundo por mor de las nuevas tecnolog\u00edas, est\u00e1n afectando radicalmente al los h\u00e1bitos de compra y consumo, a las exigencias de los ciudadanos ante un servicio. Al igual que el modelo de\u00a0 peri\u00f3dico de hace una d\u00e9cada no sirve ya, tampoco sirve el modelo de restaurante cl\u00e1sico ni el de la gesti\u00f3n del hotel de hace un lustro. Ya no sirve el \u201cno\u201d al cliente. Este tiene a su alcance u y de manera m\u00e1s inmediata que nunca, mil y una alternativas como para tener que conformarse con esa negativa.<\/p>\n<p>En definitiva, los negocios (su estructura, su gesti\u00f3n, las capacidades de su personal, incluso sus espacios) deben ajustar su talla a la del cliente, que hoy m\u00e1s que nunca, siempre tiene la raz\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si hablamos del sector tur\u00edstico (alojamiento y restauraci\u00f3n, fundamentalmente), \u00bfqu\u00e9 es la calidad? A esta pregunta (y a un carro de ellas m\u00e1s) contest\u00f3 esta semana Domenec Biosca, considerado por los profesionales del sector tur\u00edstico como el mejor experto de gesti\u00f3n y calidad hotelera y tur\u00edstica, asesor de decenas de empresas, algunas entre las grandes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,9,11],"tags":[18,31,88,108,136,187],"class_list":["post-313","post","type-post","status-publish","format-standard","hentry","category-gastronomia","category-gastroturismo","category-restauracion","category-tecnicas","tag-almirez","tag-biosca","tag-gastroturismo-2","tag-larrosa","tag-pachi","tag-turismo"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}