{"id":788,"date":"2020-03-10T18:12:43","date_gmt":"2020-03-10T17:12:43","guid":{"rendered":"https:\/\/blogs.laverdad.es\/elalmirez\/?p=788"},"modified":"2020-03-10T18:12:43","modified_gmt":"2020-03-10T17:12:43","slug":"a-la-francesa","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/elalmirez\/2020\/03\/10\/a-la-francesa\/","title":{"rendered":"A la francesa"},"content":{"rendered":"<p>El consulado del pa\u00eds vecino celebr\u00f3 su cena anual en el restaurante Monteagudo entre invitados del mundo de la diplomacia, la pol\u00edtica y la empresa<\/p>\n<div id=\"attachment_789\" style=\"width: 860px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/03\/IMG_4475.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-789\" class=\"size-full wp-image-789\" src=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/03\/IMG_4475.jpeg\" alt=\"\" width=\"850\" height=\"638\" srcset=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/03\/IMG_4475.jpeg 850w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/03\/IMG_4475-300x225.jpeg 300w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/03\/IMG_4475-768x576.jpeg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/a><p id=\"caption-attachment-789\" class=\"wp-caption-text\">El c\u00f3nsul franc\u00e9s se dirige a los invitados a la cena anual.<\/p><\/div>\n<p>\u201cEste encuentro es una forma de dar las gracias a todos los que hab\u00e9is colaborado con los franceses que viven en Murcia\u201d. Son palabras de Philippe Cazeaux, c\u00f3nsul de Francia en la Regi\u00f3n, con las que comenz\u00f3 la cena anual que convoca el Consulado del pa\u00eds vecino, en esta ocasi\u00f3n en el restaurante Monteagudo. Unas cenas que siempre tienen un \u2018leitmotiv\u2019 muy vinculado a la gastronom\u00eda y productos del pa\u00eds vecino, y que, en esta ocasi\u00f3n, gir\u00f3 de nuevo en torno al Beajulois Nouveau, el famoso vino tinto \u2018s\u00faperjoven\u2019 que se produce en la comarca del mismo nombre. La traducci\u00f3n literal de Beaujolais Nouveau es un redundante \u2018vino joven joven\u2019. Tradicionalmente es un vino que se produce para celebrar el fin de la vendimia, y est\u00e1 listo para beber a las pocas semanas de su cosecha. Se trata, por tanto, de un caldo que, te\u00f3ricamente, no podr\u00eda competir en mercados vitivin\u00edcolas ajenos a la comarca en el que se produce. Sin embargo, los 26 millones de botellas que salen a los mercados internacionales en noviembre, se venden y consumen en apenas diez d\u00edas, y en muchas ocasiones, a precios por encima de vinos locales de superior calidad.<\/p>\n<p>Phippe Cazeaux es un hombre conocido, entre otras virtudes, por su fino sentido del humor.Al comienzo del acto, los invitaos eran recibidos con una bolsita que conten\u00eda una Torre Eiffel en miniatura y una ficha numerada junto con una copa de espumoso, con la indicaci\u00f3n de que ten\u00edan que votar con esa ficha si el espumoso era un cava o un champagne. ante la incredulidad de que en un acto &#8216;tan&#8217; franc\u00e9s se cometiera le &#8216;herej\u00eda&#8217; de servir un cava, un gran n\u00famero de invitados se decant\u00f3 por el champagne&#8230; y se equivoc\u00f3.<\/p>\n<p>Entre los invitados a esta cena de 2020, varios c\u00f3nsules (Finlandia, Suecia, Polonia, M\u00e9xico, Marruecos, Ruman\u00eda\u2026), concejales de los ayuntamientos de Murcia y Cartagena, representantes de las fuerzas de Seguridad (Polic\u00eda Nacional y Guardia Civil) y de la Armada, empresarios y amigos de la legaci\u00f3n. El c\u00f3nsul revel\u00f3 que el pasado a\u00f1o aumentaron en un 37% las asistencias consulares a franceses respecto del a\u00f1o anterior. La raz\u00f3n, un significativo incremento de los turistas de esta nacionalidad, de franceses que se han registrado en el consulado y de j\u00f3venes que estudian en Murcia. De hecho, se\u00f1al\u00f3, \u201clos ciudadanos franceses son los extranjeros que m\u00e1s han hecho crecer las pernoctaciones en Murcia durante 2019\u201d. Cazeaux aprovech\u00f3 la ocasi\u00f3n para dar las gracias al Ayuntamiento de Cartagena que ayud\u00f3 al Consulado a atender al importante n\u00famero de llamadas de ayuda que recibi\u00f3 durante los episodios de Dana de finales del pasado a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El consulado del pa\u00eds vecino celebr\u00f3 su cena anual en el restaurante Monteagudo entre invitados del mundo de la diplomacia, la pol\u00edtica y la empresa \u201cEste encuentro es una forma de dar las gracias a todos los que hab\u00e9is colaborado con los franceses que viven en Murcia\u201d. Son palabras de Philippe Cazeaux, c\u00f3nsul de Francia [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3,4,5,6,8,9],"tags":[485,483,484,41,481,480,482],"class_list":["post-788","post","type-post","status-publish","format-standard","hentry","category-enologia-2","category-gastronomia","category-gastroturismo","category-historia","category-lugares","category-productos","category-restauracion","tag-beajulois","tag-caz","tag-cazeaux","tag-cena","tag-consulado","tag-francia","tag-philippe"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/comments?post=788"}],"version-history":[{"count":1,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/788\/revisions"}],"predecessor-version":[{"id":790,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/788\/revisions\/790"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/media?parent=788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/categories?post=788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/tags?post=788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}