{"id":839,"date":"2020-06-02T11:48:47","date_gmt":"2020-06-02T09:48:47","guid":{"rendered":"https:\/\/blogs.laverdad.es\/elalmirez\/?p=839"},"modified":"2020-06-02T11:48:47","modified_gmt":"2020-06-02T09:48:47","slug":"regreso-al-utero","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/elalmirez\/2020\/06\/02\/regreso-al-utero\/","title":{"rendered":"Regreso al \u00fatero"},"content":{"rendered":"<p><strong>La pandemia ha acelerado la tendencia hacia lo hiperlocal en la alta gastronom\u00eda, hacia el mundo vegetal m\u00e1s cercano al lugar donde se cocina.<\/strong><\/p>\n<p><a href=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-840\" src=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh.jpg 1280w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh-300x225.jpg 300w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh-768x576.jpg 768w, https:\/\/blogs.laverdad.es\/elalmirez\/wp-content\/uploads\/sites\/38\/2020\/06\/vegetable-garden-133441298497619Nzh-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a>Dos fuerzas se han unido para provocar una reacci\u00f3n igual a la suma de ambas (si hacemos caso a la segunda ley de Newton): la comprobaci\u00f3n, tras el confinamiento, de que en casa estamos protegidos, y el rechazo a aglomeraciones y contactos m\u00e1s all\u00e1 del \u00e1mbito de la unidad familiar o, como mucho, de la familia extensa. La Covid-19 es, tambi\u00e9n, un agente de cambio de los h\u00e1bitos de vida. Para empezar , el gran impulso al teletrabajo ha roto el v\u00ednculo espacial entre residencia y centro de trabajo. En muchos casos, ya no es necesario condicionar la primera al segundo, proporcionando m\u00e1s libertad de elecci\u00f3n. Las inmobiliarias lo registran: se trata de buscar viviendas con m\u00e1s espacio que proporcionen mayor calidad de vida. Y eso solo se consigue (si uno no es millonario) alej\u00e1ndose de los n\u00facleos urbanos. Y es que el coronavirus tambi\u00e9n est\u00e1 poniendo en cuesti\u00f3n un modelo de ciudad que hasta ahora era ejemplo de eficiencia y sostenibilidad: la ciudad en vertical, con Benidorm como icono en nuestro pa\u00eds, que provocan una alta densidad de poblaci\u00f3n.<\/p>\n<p>Esa especie de \u2018retorno al \u00fatero materno\u2019, a lo cercano, a lo reconocible y por tanto, m\u00e1s controlable es una de las consecuencias del paso de la pandemia. Se manifiesta con claridad en las tendencias que se avanzan en el \u00e1mbito de la alta gastronom\u00eda. Este \u2018frenazo\u2019 al vertiginoso ritmo en el que se mov\u00edan las sociedades avanzadas ha obligado a templar y mirar con un ojo hacia delante y otro hacia atr\u00e1s, hacia lo esencial, hacia lo despojado de sofisticaci\u00f3n y artificio prescindible. Seg\u00fan el chef portugu\u00e9s Henrique Sa Pessoa, \u201cse potenciar\u00e1 la cocina de la memoria. No desaparecer\u00e1 la creatividad, pero se frenar\u00e1\u201d. Por una cuesti\u00f3n de costes y de obligadas bajadas de precio, \u201cla creatividad tendr\u00e1 que expresarse m\u00e1s que en los platos, en los modelos y en la gesti\u00f3n de los negocios\u201d.<\/p>\n<p>Esa vuelta a lo local, que ya se ven\u00eda observando en las dos \u00faltimas ediciones de Madrid Fusi\u00f3n y San Sebasti\u00e1n Gastronomika, pasa tambi\u00e9n por una labor de recuperaci\u00f3n de la producci\u00f3n y los productores locales. Si el chef brasile\u00f1o Alex Atala aboga por \u201cla recuperaci\u00f3n de ingredientes aut\u00f3ctonos y desconocidos o casi perdidos\u201d, el cocinero valenciano Ricard Camarena defiende que \u201chay que revalorizar el campo, al peque\u00f1o productor alejado de las grandes plataformas y para eso es necesaria una labor previa de educaci\u00f3n mutua entre el cocinero y el productor\u201d. Si el chef catal\u00e1n Albert Raurich pone a Jap\u00f3n como ejemplo de apego a la estacionalidad de los productos y de su lucha contra la universalizaci\u00f3n del gusto, la italiana Vivian Varese apela al movimiento Slow Food (nacido en Italia) y defiende volver a una suerte de \u201cnacionalismo gastron\u00f3mico\u201d<\/p>\n<p>En cuanto al turismo, las tendencias corren paralelas, animadas por esa especie de repliegue hacia un mayor asilamiento, en la b\u00fasqueda de esa \u2018sensaci\u00f3n caba\u00f1a\u2019. Todos los datos del sector ya apuntan al turismo de proximidad como una tendencia en crecimiento, con la vivienda vacacional y los apartamentos de costa como primera opci\u00f3n de alojamiento. En una especie de vuelta a la Espa\u00f1a de \u2018Cu\u00e9ntame\u2019, se valora m\u00e1s que nunca la \u2018casa del pueblo\u2019.<\/p>\n<p>De hecho, seg\u00fan una encuesta de Ernest&amp;Young realizado a principios de mayo, solo un 17% de los futuros veraneantes buscar\u00e1n un hotel para alojarse. Y quien no tiene casa en el pueblo (aqu\u00ed en Murcia, \u2018la casa de la playa\u2019, todo un concepto identitario), tirar\u00e1 de las casas rurales. Es su momento. La hu\u00edda de las zonas de mayor aglomeraci\u00f3n por temor a la Covid-19 est\u00e1 incrementando la demanda de este tipo de alojamiento, que permite espacios m\u00e1s amplios y mayor seguridad para las unidades familiares, lo que est\u00e1 provocando una subida de los precios. Nada menos que un 29% es el \u00edndice de crecimiento en la preferencia de los consumidores por estos destinos cercanos y en plena naturaleza, para los que no es necesario usar transportes colectivos. Y para quien se lo pueda permitir, el alquiler de chalets con piscina privada, cuya demanda tambi\u00e9n est\u00e1 aumentando. En resumen: que se preparen los de la Espa\u00f1a vaciada, a ver si ahoravan a acabar ech\u00e1ndola de menos.<\/p>\n<p>\u2018Slow Food\u2019: comer local, comer despacio, vivir despacio. Una utop\u00eda que podr\u00eda estar m\u00e1s cerca tras el inesperado impacto de un virus que ha puesto del rev\u00e9s a nuestras sociedades. La pregunta es si valdr\u00e1 la pena el precio pagado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La pandemia ha acelerado la tendencia hacia lo hiperlocal en la alta gastronom\u00eda, hacia el mundo vegetal m\u00e1s cercano al lugar donde se cocina. Dos fuerzas se han unido para provocar una reacci\u00f3n igual a la suma de ambas (si hacemos caso a la segunda ley de Newton): la comprobaci\u00f3n, tras el confinamiento, de que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,5,6,7,8,9,10],"tags":[490,85,98,443,493,380,512,489],"class_list":["post-839","post","type-post","status-publish","format-standard","hentry","category-gastronomia","category-gastroturismo","category-historia","category-lugares","category-noticia","category-productos","category-restauracion","category-sin-categoria","tag-covid","tag-gastronomia-2","tag-huerta","tag-local","tag-pandemia","tag-tendencias","tag-vegetal","tag-virus"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":1,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"predecessor-version":[{"id":841,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/posts\/839\/revisions\/841"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/elalmirez\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}