{"id":1626,"date":"2019-10-20T22:55:40","date_gmt":"2019-10-20T20:55:40","guid":{"rendered":"https:\/\/blogs.laverdad.es\/musicainesperada\/?p=1626"},"modified":"2019-10-20T23:11:27","modified_gmt":"2019-10-20T21:11:27","slug":"ciego-por-obsesion","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/musicainesperada\/2019\/10\/20\/ciego-por-obsesion\/","title":{"rendered":"Ciego por obsesi\u00f3n"},"content":{"rendered":"<p>El Gran Teatro del Liceo de Barcelona inaugura la temporada en la que celebra su 20 aniversario con una producci\u00f3n de <em><strong>Turandot<\/strong><\/em>, la \u00f3pera que dej\u00f3 sin concluir <strong>Giacomo Puccini<\/strong> impedido por una grave enfermedad lar\u00edngea.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Entre las virtudes m\u00e1s sobresalientes en las que destac\u00f3 <strong>Puccini<\/strong> estaba su capacidad para describir la personalidad femenina con m\u00fasica, a trav\u00e9s de mujeres en escena como Tosca, Madama Butterfly, Mim\u00ed, Manon o Minnie, entre otras.<\/p>\n<p>Parad\u00f3jicamente, en <em><strong>Turandot<\/strong><\/em>, la hero\u00edna de <strong>Puccini<\/strong> no es la \u201cprincesa de hielo\u201d que da nombre a la \u00f3pera, sino Li\u00fa, el otro personaje femenino que con su humanidad conmovedora, es perfectamente cre\u00edble ante nosotros hasta el punto de agitarnos emocionalmente.<\/p>\n<p>De una manera rotunda, podemos decir que Li\u00fa es la mujer que mejor representa como el compositor italiano maneja los temas delicados. En otra ocasi\u00f3n ya les habl\u00e9 del &#8220;instinto neroniano&#8221; de <strong>Puccini<\/strong> refiri\u00e9ndome a su capacidad para alternar entre la m\u00e1s terrible crueldad y el amor m\u00e1s puro.<\/p>\n<p>En el primer acto de la \u00f3pera, Calaf, el pr\u00edncipe desconocido, llega a la corte de Turandot en Pek\u00edn y se enamora de ella. All\u00ed se da a conocer como un nuevo pretendiente para casarse con la princesa en contra de las advertencias de su padre, de su sirvienta Li\u00fa y de tres m\u00e1scaras que resultan ser los ministros del emperador. Calaf decide someterse con determinaci\u00f3n a los tres acertijos que \u201cla princesa de hielo\u201d le propone<span class=\"Apple-converted-space\">\u00a0 <\/span>a sabiendas de que un error significar\u00eda su muerte.<\/p>\n<p>Una vez m\u00e1s, la \u00f3pera de <strong>Puccini<\/strong> muestra la naturaleza humana y la credibilidad de un enamorado que, preso de la obsesi\u00f3n, no atiende a los consejos y a advertencias para llevar a cabo su empresa.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Tanto se centra la atenci\u00f3n de Calaf en Turandot que<span class=\"Apple-converted-space\">\u00a0<\/span>permite at\u00f3nito que la mujer que lo ama, Li\u00fa, sea torturada y finalmente se quite la vida, una vez que ella entiende que su amor hacia el pr\u00edncipe es imposible y que su gesto protege su identidad y por tanto su vida.<\/p>\n<p><strong>Puccini<\/strong> dej\u00f3 de escribir en la partitura de <em><strong>Turandot<\/strong><\/em> justo cuando muere Li\u00fa, hecho que tiene un claro reflejo en la producci\u00f3n que se est\u00e1 representando en el Liceo. Al final de la \u00f3pera, Turandot descubre que es una mujer con capacidad para amar, pero a diferencia de la versi\u00f3n original completada por <strong>Alfano<\/strong> en la que se casa con Calaf, en la propuesta de Barcelona, la princesa besa a la yacente Li\u00fa al tiempo que el coro se desnuda para despertar de la irrealidad que est\u00e1 viviendo.<\/p>\n<p><strong>Turandot<\/strong> es una obra de arte en cuanto a melod\u00edas, armon\u00edas, orquestaci\u00f3n, corales y colorido, pero ante todo es un alegato al amor puro y una lecci\u00f3n de humanidad. Parece que el destino ha querido que estos d\u00edas sea representada en Barcelona, donde la convivencia democr\u00e1tica es traicionada por la barbarie independentista.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/h34omCNzK9g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gran Teatro del Liceo de Barcelona inaugura la temporada en la que celebra su 20 aniversario con una producci\u00f3n de Turandot, la \u00f3pera que dej\u00f3 sin concluir Giacomo Puccini impedido por una grave enfermedad lar\u00edngea.\u00a0 Entre las virtudes m\u00e1s sobresalientes en las que destac\u00f3 Puccini estaba su capacidad para describir la personalidad femenina con [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,8],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1626"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/comments?post=1626"}],"version-history":[{"count":5,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1626\/revisions"}],"predecessor-version":[{"id":1631,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1626\/revisions\/1631"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/media?parent=1626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/categories?post=1626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/tags?post=1626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}