{"id":1845,"date":"2020-08-30T21:21:30","date_gmt":"2020-08-30T19:21:30","guid":{"rendered":"https:\/\/blogs.laverdad.es\/musicainesperada\/?p=1845"},"modified":"2020-08-30T21:21:30","modified_gmt":"2020-08-30T19:21:30","slug":"componiendo-toses","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/musicainesperada\/2020\/08\/30\/componiendo-toses\/","title":{"rendered":"Componiendo toses"},"content":{"rendered":"<p><a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42.png\"><img loading=\"lazy\" class=\"alignright size-full wp-image-1847\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42.png\" alt=\"\" width=\"1306\" height=\"596\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42.png 1306w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42-300x137.png 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42-768x350.png 768w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/23\/2020\/08\/Captura-de-pantalla-2020-08-30-a-las-21.19.42-1024x467.png 1024w\" sizes=\"(max-width: 1306px) 100vw, 1306px\" \/><\/a><\/p>\n<p>La m\u00fasica refleja muy bien las inquietudes de las personas como disciplina human\u00edstica de lenguaje universal que es, mostr\u00e1ndose comprensible m\u00e1s all\u00e1 de las fronteras establecidas. La enfermedad infecciosa tampoco entiende de l\u00edmites geogr\u00e1ficos, tal y como vemos en la pandemia por coronavirus que actualmente asola al planeta.<\/p>\n<p>Covid-19 no es la primera epidemia importante a la que se ha enfrentado el ser humano, cuya fragilidad ante el rigor de la Madre Naturaleza es a\u00fan m\u00e1s patente por el desconocimiento e incertidumbre que nos rodea.<\/p>\n<p>No tenemos que retroceder mucho en la Historia para reconocer como la M\u00fasica y la Literatura, entre otras disciplinas art\u00edsticas, van de la mano de la situaci\u00f3n socioecon\u00f3mica y cient\u00edfico-t\u00e9cnica de cada \u00e9poca.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Cuando el hombre decidi\u00f3 domesticar a la Naturaleza, no tuvo en cuenta que \u00e9sta apareci\u00f3 mucho antes que \u00e9l y que los microorganismos que la habitan son m\u00e1s astutos que nosotros y son capaces de mutar para sobrevivir. Han sido muchas las infecciones que han asolado nuestro planeta (peste bub\u00f3nica, s\u00edfilis, viruela, SIDA\u2026) pero la que quiz\u00e1s ha tenido m\u00e1s repercusi\u00f3n en el mundo del arte ha sido la tuberculosis, una enfermedad que lleg\u00f3 a infectar durante la primera mitad del siglo XIX a la mitad de la poblaci\u00f3n de Gran Breta\u00f1a, causando la muerte al tercio de sus habitantes. Hoy d\u00eda, la tisis, como tambi\u00e9n se denomina este proceso infeccioso, causa un mill\u00f3n y medio de muertes cada a\u00f1o, adem\u00e1s de las repercusiones emocionales que ocasiona a los que la sufren.<\/p>\n<p>La \u00f3pera es un espejo que nos devuelve la situaci\u00f3n social y cient\u00edfica del momento en el que se crearon las composiciones. Antes de descubrimiento del bacilo de Koch como gen responsable de la tuberculosis (1882), se desconoc\u00eda la naturaleza infecciosa de la tisis. En general, la tuberculosis se asociaba a un ideal de belleza donde la mirada brillante, las mejillas sonrosadas y la sudoraci\u00f3n de la p\u00e1lida piel contribu\u00edan al aura de fragilidad y pureza propias de las mujeres sexualmente atractivas y bellas. Hubo tres estrenos oper\u00edsticos que traducen c\u00f3mo era el entorno social de cada momento: el de la Traviata, el de Los cuentos de Hoffmann y el de La Boheme.<\/p>\n<p><em><strong>La Traviata<\/strong><\/em> fue estrenada por <strong>Verdi<\/strong> en Venecia en 1853, \u00e9poca en la que todo el mundo parec\u00eda que iba a morir lentamente de tuberculosis, padecimiento que ten\u00eda una dimensi\u00f3n m\u00e1s social que m\u00e9dica y que se entend\u00eda como un acto de redenci\u00f3n (sacrificio f\u00edsico) en personas cuyos pecados eran consecuencia de la sociedad donde vive. Hasta ese momento, los compositores prefer\u00edan que sus sopranos se suicidaran para lograr la salvaci\u00f3n, pero con Verdi esto cambi\u00f3. As\u00ed, Violetta Valery, nuestra protagonista, arrastra un pasado escandaloso que le va a impedir culminar su historia de amor con Alfredo. Como en esa \u00e9poca la tuberculosis no era considerada una infecci\u00f3n, Alfredo se comporta como un aut\u00e9ntico enamorado que ansia estar con Violetta hasta el final. La salvaci\u00f3n del alma de la protagonista es \u00fanicamente posible a trav\u00e9s de la muerte y todos los personajes la ven como una buena mujer hostigada por las circunstancias y prejuicios sociales.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Otra c\u00e9lebre tuberculosa es Antonia, la hero\u00edna de <em><strong>Los cuentos de Hoffmann<\/strong><\/em> de <strong>Jacques Offenbach<\/strong>, estrenada en el Teatro Nacional de la \u00d3pera de Par\u00eds un a\u00f1o antes del descubrimiento del bacilo de Koch. En esa \u00e9poca se consideraba que la tuberculosis era un mal hereditario y los m\u00e9dicos solo pod\u00edan hacer un pron\u00f3stico evolutivo del padecimiento. En el libreto, Hoffmann hace una cr\u00edtica sobre las limitaciones cient\u00edficas a trav\u00e9s del personaje Dr. Miracle, un m\u00e9dico charlat\u00e1n que no evita la muerte de Antonia a la que aplica remedios sin sentido. \u00c9sta, a diferencia de Violetta, muere enloquecida por la enfermedad, sin comprender lo que le pasa y sin que exista ninguna explicaci\u00f3n moral.<\/p>\n<p>Finalmente, en 1896, cuando todos supimos que la tisis era contagiosa y m\u00e1s propia de ambientes cerrados, sucios y mal ventilados, <strong>Puccini<\/strong> estrena <em><strong>La Boheme<\/strong><\/em> en Tur\u00edn. La protagonista es Mim\u00ed, una bella joven tambi\u00e9n condenada a morir de tuberculosis que, a diferencia de Violetta, est\u00e1 enamorada de un escritor (Rodolfo) consciente del car\u00e1cter infeccioso de su enfermedad. Por ello, cuando arrecia la tos de Mimi, la rechaza y le recomienda que se vaya con su amante rico para que la cuide mejor. En la escena final, es muy significativo como Mim\u00ed muere rodeada del arrepentido poeta en presencia de sus amigos (un fil\u00f3sofo, un pintor, un m\u00fasico y un cantante), reflejando la impotencia de las disciplinas art\u00edsticas ante una enfermedad contagiosa que afectaba muy especialmente a las clases sociales m\u00e1s pobres.<\/p>\n<p>Las condiciones de los menos favorecidos que delataban a la sociedad como culpable de los males del ser humano es el tema de uno de los musicales de m\u00e1s \u00e9xito en nuestros tiempos. En <em><strong>Los Miserables<\/strong><\/em>, basado en la novela publicada por <strong>Victor Hugo<\/strong> en 1862, el protagonista (Jean Valjean) es un hombre acosado que encuentra la redenci\u00f3n al adoptar a la hija de Fantine, una mujer honrada que se ve obligada a prostituirse y rebajarse hasta la desesperanza, falleciendo de tuberculosis.<\/p>\n<p>En 1952 empieza la era de los f\u00e1rmacos tuberculost\u00e1ticos, tan ansiados como la vacuna para el coronavirus que hoy esperamos, pero que no han conseguido erradicar la enfermedad ni sus consecuencias. Curiosamente, desde las primera concepci\u00f3n rom\u00e1ntica del padecimiento &#8211; equiparado a una determinada constituci\u00f3n que favorec\u00eda la creatividad-, hasta la idea basada en la ciencia actual, no hemos conseguido erradicar la tisis de nuestro planeta. Hoy sigue habiendo muchas Violettas, Antonias, Mimis y Fantines en el mundo, todas ellas mujeres que sufren, mueren y son queridas por otras personas.<\/p>\n<p>Por ello, en la actual pandemia por coronavirus, adem\u00e1s de ofrecer lo mejor de nosotros para superarla, hay que esforzarse en no contrariar m\u00e1s a la Madre Naturaleza y, si es posible, agradecerle sus bondades con la mejor m\u00fasica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00fasica refleja muy bien las inquietudes de las personas como disciplina human\u00edstica de lenguaje universal que es, mostr\u00e1ndose comprensible m\u00e1s all\u00e1 de las fronteras establecidas. La enfermedad infecciosa tampoco entiende de l\u00edmites geogr\u00e1ficos, tal y como vemos en la pandemia por coronavirus que actualmente asola al planeta. Covid-19 no es la primera epidemia importante [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1845"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/comments?post=1845"}],"version-history":[{"count":2,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1845\/revisions"}],"predecessor-version":[{"id":1848,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/posts\/1845\/revisions\/1848"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/media?parent=1845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/categories?post=1845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/musicainesperada\/wp-json\/wp\/v2\/tags?post=1845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}