{"id":20,"date":"2011-10-24T17:51:56","date_gmt":"2011-10-24T17:51:56","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=20"},"modified":"2011-10-24T17:51:56","modified_gmt":"2011-10-24T17:51:56","slug":"nativel-preciado-nadie-pudo-con-ellos","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2011\/10\/24\/nativel-preciado-nadie-pudo-con-ellos\/","title":{"rendered":"Nativel Preciado &#8220;Nadie pudo con ellos&#8221;"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/3.bp.blogspot.com\/-zKyxrYEpMaU\/TqRb3mY0YvI\/AAAAAAAABzI\/uje-noPoruk\/s1600\/nativel.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"213\" src=\"\/\/3.bp.blogspot.com\/-zKyxrYEpMaU\/TqRb3mY0YvI\/AAAAAAAABzI\/uje-noPoruk\/s320\/nativel.jpg\" width=\"320\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\nNativel Preciado gran amiga, gran periodista<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<p>Nativel acaba de publicar un libro que he de recomendarles. Se titula &#8220;Nadie pudo con ellos&#8221;, no lo hago por simpat\u00eda, ya saben que las Gracia somos brutalmente sinceras y, a fuerza de perder amigos, he aprendido a morderme la lengua (las verdades brutales, me parece, no le gustan a nadie) pero en este caso no pueden quedar en el silencio las sensaciones, im\u00e1genes, los olores que percib\u00ed con el nuevo libro de Nativel Preciado, que todos los pol\u00edticos deber\u00edan leer. Los cachorros de la pol\u00edtica mucho m\u00e1s porque no hay nada peor que un cachorro adoctrinado sin capacidad de discernimiento, autocr\u00edtica o juicio propio.<br \/>\nHay im\u00e1genes entra\u00f1ables en &#8220;Nadie pudo con ellos&#8221; como la de Josefina Samper levant\u00e1ndose a las tres de la ma\u00f1ana para preparar una olla de comida para los presos de Franco en Carabanchel. Entre esos presos, por supuesto, estaba su marido, el insobornable y valeroso Marcelino Camacho. Se le han hecho tantos homenajes a pol\u00edticos de la transici\u00f3n, a &#8220;personajes&#8221; que lo merec\u00edan mucho menos que \u00e9l y que, bajo mi punto de vista, &nbsp;ingenuo y desconocedor de la absoluta verdad de aquellos a\u00f1os, no contaron con su valor, su capacidad de sacrificio y su humildad que ya era hora \u00bfverdad Nativel?. Mientras otros se marchaban al exilio \u00e9l se qued\u00f3 y luch\u00f3 por los derechos de los trabajadores y de los espa\u00f1oles oprimidos.<\/p>\n<p>Nativel ha hecho justicia con este libro, consigue lo que muy pocos grandes literatos logran: escuchamos las voces de los protagonistas, sin dejar de escuchar su voz propia, pr\u00edstina, di\u00e1fana. Recuerdo que me cont\u00f3 lo que dijo un d\u00eda I\u00f1aki Gabilondo de su estilo: escribe sobre el cristal (m\u00e1s o menos, escribo de memoria). No podr\u00eda definirlo mejor.<\/p>\n<p>Tengo la teor\u00eda de que los escritores narran seg\u00fan la cara que tienen. Lo s\u00e9, es una idea alocada, quiz\u00e1 absurda. Pero no, la experiencia me lo demuestra una y otra vez. Nativel es as\u00ed, como este libro. Tiene la humildad necesaria para eliminar con limpieza de cirujano todos los efectos especiales posibles que cabr\u00edan en un relato como este: no hay nostalgia, no hay sentimentalismo, no hay met\u00e1foras baratas. Hay una realidad que palpita. Hay dolor, hay repulsa contra las injusticias cometidas y hay una gran generosidad hacia sus lectores.<\/p>\n<p>Pero no se enga\u00f1en, detr\u00e1s de la generosidad y bondad de Nativel, se esconde una gran, gran seductora. A su manera, con su suavidad indiscutible, se encuentra una periodista de raza, una escritora de raza que te agarra por la solapas en cuanto te descuidas y te &#8220;obliga&#8221; a leerte sus libros de tir\u00f3n. A mi me ha pasado con todos y cada uno de ellos. Recuerdo esa sobrecogedora experiencia la primera vez que cay\u00f3 en mis manos &#8220;El ego\u00edsta&#8221;, finalista del premio Planeta.<\/p>\n<p>Nativel consigue que parezca sencillo escribir como ella lo hace. Y no lo es. En absoluto. Consigue lo que s\u00f3lo logran los virtuosos: tocan, bailan pintan como si respirasen. Ella escribe como si respirase, sin esfuerzo (aparentemente) con una brutal naturalidad.<br \/>\nNativel ha conseguido el objetivo marcado en su pr\u00f3logo: &#8220;Hagamos memoria, a ser posible, sin manipulaciones interesadas o recuerdos alterados por el paso del tiempo&#8221;. Lo ha conseguido.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nativel Preciado gran amiga, gran periodista Nativel acaba de publicar un libro que he de recomendarles. Se titula &#8220;Nadie pudo con ellos&#8221;, no lo hago por simpat\u00eda, ya saben que las Gracia somos brutalmente sinceras y, a fuerza de perder amigos, he aprendido a morderme la lengua (las verdades brutales, me parece, no le gustan [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[185,190,204,206,208,212,213,214],"class_list":["post-20","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-espasa","tag-guerra-civil","tag-libros","tag-lola-gracia","tag-marcelino-camacho","tag-mujeres","tag-nadie-pudo-con-ellos","tag-nativel-preciado"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/20\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=20"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=20"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}