{"id":25,"date":"2011-11-21T20:18:12","date_gmt":"2011-11-21T20:18:12","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=25"},"modified":"2011-11-21T20:18:12","modified_gmt":"2011-11-21T20:18:12","slug":"julia-otero-not-for-sale","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2011\/11\/21\/julia-otero-not-for-sale\/","title":{"rendered":"Julia Otero, not for sale"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/1.bp.blogspot.com\/-HBw0QXcJMLY\/Tor0eeG5N2I\/AAAAAAAABxY\/LOe4i9xH_hs\/s1600\/10148_julia-otero.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"320\" src=\"\/\/1.bp.blogspot.com\/-HBw0QXcJMLY\/Tor0eeG5N2I\/AAAAAAAABxY\/LOe4i9xH_hs\/s320\/10148_julia-otero.jpg\" width=\"229\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<p>Recuerdo la primera vez que alguien me habl\u00f3 de Julia Otero. Fueron mis hermanos. Yo estudiaba en Madrid, no ve\u00eda la tele en absoluto y en uno de mis &nbsp;&#8220;regreso al hogar&#8221;, Pedro me insisti\u00f3: &#8220;Tienes que ver esto&#8221;. Era el 3&#215;4. Julia nos embob\u00f3 a todos con su pelo pincho, su rapidez, su desparpajo, su gracia. Despu\u00e9s la vimos realizar entrevistas magistrales en La Luna. Y era tan joven. Tan joven y tan experta. Paul MacArtney, Pertegaz, Guerra, Paloma Picasso. Julia era y es una gran entrevistadora. Ha demostrado con creces que para ella entrevistar es respirar y transpirar. Era una televisi\u00f3n mimada al detalle. Luego vino la Ronda y despu\u00e9s volv\u00eda a la radio en 1991. Y ah\u00ed la voz de Julia, su encanto, su tenacidad, su temple, su terquedad, su pluralismo, su generosidad, su frescura, su estilo tan moderno, &nbsp;me atraparon para siempre. Era el tiempo de las sinton\u00edas de Kenny G, cuando casi nadie sab\u00eda quien era, s\u00f3lo mi amigo Juanillo, y cuando La radio de Julia era por la noche. Despu\u00e9s pas\u00f3 a las tardes. Iba de mis clases de idiomas, a las de baile, a mis citas con amigos por Madrid con mis walkman y Julia, siempre Julia. Sus risas incontenibles con Acad\u00e9mica Palanca, las broncas a los gabineteros porque &nbsp;&#8220;aquello parec\u00eda un gallinero&#8221;. Otra vez, su gran estilo, su altura comunicadora y su cercan\u00eda. Qu\u00e9 dif\u00edcil llegar a ambos extremos.<br \/>\nJulia es muy grande, s\u00f3lo ella ha conseguido m\u00e1s de medio mill\u00f3n de oyentes en la tarde y dos millones en la tele y, a un tiempo, es muy cercana. Al menos para mi siempre lo ha sido. Los seis meses que estuve en Puerto Rico apenas extra\u00f1\u00e9 Espa\u00f1a, salvo por el programa de Julia (all\u00ed yo realizaba mi propio programita y en el viejo San Juan abr\u00eda la boca y todos me dec\u00edan &#8220;Ah, tu ereh la ehpa\u00f1ola de Radio Universidad&#8221;). Ya exist\u00eda radio por Internet &nbsp;pero no ten\u00eda computadora, s\u00f3lo una vieja y el\u00e9ctrica m\u00e1quina de escribir que pesaba una tonelada.<br \/>\nRecuerdo aquel fat\u00eddico d\u00eda que sus m\u00e1s de 500 mil oyentes nos quedamos hu\u00e9rfanos. Lo que le hicieron a Julia, a nosotros, fue una canallada. Todos sabemos de donde sali\u00f3. Los nombres de Aznar y C\u00e9sar Alierta se unieron para hacer esto tan vil, tan feo. Lo recuerdo como si fuera ayer. En la radio estaba aquel tipo que s\u00f3lo habla de m\u00fasica.<br \/>\nHubo una \u00e9poca de silencio. Ella sigui\u00f3 haciendo tele en Catalu\u00f1a. Pude ver algunas &#8220;Columnas&#8221;, pudimos leer algunas columnas, de las otras, en El Pa\u00eds. Julia, aparte de su oralidad magn\u00edfica tambi\u00e9n escribe muy bien. Es casi perfecta en todo la muy pu\u00f1etera, qu\u00e9 se le va hacer; lleg\u00f3 la \u00e9poca de Punto Radio, volvi\u00f3<br \/>\na la tele con &#8220;Las cerezas&#8221; y por fin regres\u00f3 a Onda Cero.<br \/>\nEl hecho de reecontrarme con ella por Twitter ha sido una de las pocas alegr\u00edas de este 2011, de grandes ilusiones, de preciosos momentos, pero tan duro, por dios. A veces nos escribimos. A veces nos hacemos gui\u00f1os. Qu\u00e9 honor. Porque ella es honorable. Una mujer admirable, supertrabajadora. Siempre al pie del ca\u00f1\u00f3n, en la trinchera. Abierta a los comentarios de sus oyentes a quienes quiere y respeta. Dir\u00eda incluso que tiene una historia de amor con ellos, con todos nosotros, que es rec\u00edproca.&nbsp;Que nadie me la critique porque puedo asestarle una descomunal colleja. &nbsp;Tiene todo el derecho del mundo a ser parcial, a mostrar sus opiniones. Todos los comunicadores lo hacen de un modo u otro pero ella va de frente, es irremediablemente directa y eso todav\u00eda no lo digieren determinados sectores de esta nuestra sociedad democr\u00e1tica. Y menos en una mujer. Mujer ten\u00edas que ser, Julia Otero. Pero no una, sino muchas, como cantaba Chaka Khan en esa canci\u00f3n que tanto te gusta &#8220;I&#8217;m every woman&#8221;.<\/p>\n<p>La \u00fanica pega que tengo contigo, Julia, es que te admiro tanto que me impones una barbaridad. Cuando alguna vez particip\u00e9 en tus programas (en aquello de las tribus) me sent\u00eda algo est\u00fapida. Me pasa siempre cuando conozco a alguien que he admirado tanto y tan largo. Me cuesta romper la barrera del fan,en el fondo, una fan muy t\u00edmida aunque parezca que me como el mundo.<br \/>\nAlgo habr\u00e1 que hacer \u00bfverdad? Quiz\u00e1, alg\u00fan d\u00eda, nos tomemos una ca\u00f1a en alg\u00fan sitio o nos vayamos de fiesta, a bailar (nada de entregas de premios ni cosas por el estilo) una fiesta sin metas. Despu\u00e9s de tanto correr, corredora de fondo como eres, algo de juerga no te vendr\u00eda mal. As\u00ed, sin objetivos. No me da pudor el escribirlo y el decirlo: que te quiero mucho, Julia; que eres muy grande como comunicadora. Como persona, a\u00fan m\u00e1s y que ten\u00eda que escribir esto en mi blog.Te escucho.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Recuerdo la primera vez que alguien me habl\u00f3 de Julia Otero. Fueron mis hermanos. Yo estudiaba en Madrid, no ve\u00eda la tele en absoluto y en uno de mis &nbsp;&#8220;regreso al hogar&#8221;, Pedro me insisti\u00f3: &#8220;Tienes que ver esto&#8221;. Era el 3&#215;4. Julia nos embob\u00f3 a todos con su pelo pincho, su rapidez, su desparpajo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}