{"id":26,"date":"2011-11-26T11:45:25","date_gmt":"2011-11-26T11:45:25","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=26"},"modified":"2011-11-26T11:45:25","modified_gmt":"2011-11-26T11:45:25","slug":"casi","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2011\/11\/26\/casi\/","title":{"rendered":"Casi"},"content":{"rendered":"<p>Me paso la vida en los casi. Rozando el cielo con la punta de los dedos&#8230;pero el cielo est\u00e1 ah\u00ed, a dos palmos de mis manos. En ocasiones, me encaramo a un trozo de nube y vislumbro el Caribe. Cruzo el atl\u00e1ntico en sue\u00f1os, gracias a los mails de algunos amigos. Quisiera estar ah\u00ed con ellos. Chicago, L.A. NY. Cualquier sitio es bueno para escapar de esta realidad tan tozuda y terrible que vivimos. Gonzalo me acompa\u00f1a en la fuga muchas veces. Es experto en inventarse universos. La m\u00fasica, el baile y, sobre todo,las risas, la lealtad de los amigos, de la gente que te quiere bien y que t\u00fa quieres, te mantienen en pie. Se niegan a verte caer. Tantas veces he estado a punto de&#8230;.Pero no llega. No llego. Almost. Ese es mi estado. Un standby insoportable.<br \/>\n Albert Pl\u00e1 le dijo a Julia Otero el otro d\u00eda que a \u00e9l le gusta hacer canciones y ya est\u00e1, sin metas. Es una buena manera de plantearse la vida. Yo disfruto comunicando. Una barbaridad. Pero me queman las horas. Todo est\u00e1 a flor de piel y todo es r\u00e1pido, intenso, veloz. Pero, a la vez, me tortura una idea: la de malgastar el precioso tiempo que vivimos. Cuando hecho la vista atr\u00e1s y hago resumen de este 2011 (ya va tocando) contemplo muchas escenas: reuniones, llamadas, m\u00e1s reuniones, m\u00e1s llamadas; cientos y cientos de correos electr\u00f3nicos; unos cuantos tweets (hasta el momento 5.782), entradas al blog, a facebook. Incontables horas frente al ordenador. Algunos resultados, s\u00ed \u00bfPero merece la pena tanta lucha?. Me aterra perder el tiempo. Quiz\u00e1 no debiera malgastar una l\u00ednea y saltar, volar, jugar, olvidarme del mundo, porque en ocasiones creo que el mundo se ha olvidado de mi.<br \/>\nCierto, el que m\u00e1s y el que menos tiene esta sensaci\u00f3n. Son 20 a\u00f1os de sensaci\u00f3n. Ya est\u00e1 bien. Hace una d\u00e9cada le confes\u00e9 a un amigo mi idea de abandonarlo todo, dedicarme a otra cosa. \u00c9l, muy tierno, me escribi\u00f3 que me libraba de estar fuera de su alcance porque me iba a dar la colleja m\u00e1s grande de la historia. Ahora ya es tarde. No s\u00e9 hacer otra cosa que esto. Observar la realidad. Comunicar la realidad y refugiarme siempre que puedo en ese cosmos del cine, la m\u00fasica, la literatura&#8230;las artes.<br \/>\nA lo mejor me pasa como a Albert Pl\u00e1&#8230;no quiero terminar esta canci\u00f3n porque me encanta hacer canciones, porque me encanta escribir art\u00edculos, porque me encanta vivir en el casi.<a href='http:\/\/www.youtube.com\/watch?feature=player_embedded&#038;v=NJiC6cA3dUA#!' >Here comes the sun<\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me paso la vida en los casi. Rozando el cielo con la punta de los dedos&#8230;pero el cielo est\u00e1 ah\u00ed, a dos palmos de mis manos. En ocasiones, me encaramo a un trozo de nube y vislumbro el Caribe. Cruzo el atl\u00e1ntico en sue\u00f1os, gracias a los mails de algunos amigos. Quisiera estar ah\u00ed con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}