{"id":373,"date":"2013-01-24T07:41:23","date_gmt":"2013-01-24T07:41:23","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=373"},"modified":"2013-01-24T07:41:23","modified_gmt":"2013-01-24T07:41:23","slug":"body-sushi","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/01\/24\/body-sushi\/","title":{"rendered":"Body sushi"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/-mMxn7Fm2NPY\/UQDkcyW9eJI\/AAAAAAAACKU\/1svaBWzfOrg\/s1600\/Body_Sushi_by_mmonart.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/3.bp.blogspot.com\/-mMxn7Fm2NPY\/UQDkcyW9eJI\/AAAAAAAACKU\/1svaBWzfOrg\/s320\/Body_Sushi_by_mmonart.jpg\" alt=\"\" width=\"320\" height=\"213\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Me ser\u00eda imposible ser modelo de Body Sushi \u00a1Imaginaos qu\u00e9 cosquillas! Y, por favor, \u00a1Qu\u00e9 verg\u00fcenza! Todas las lorzas al aire y unos t\u00edos husme\u00e1ndome el sobaco. Horroroso, horroroso.<\/span><span style=\"font-family: arial, sans-serif;\">\u00a0<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Tampoco comer\u00eda sushi del cuerpo de un caballero, por bueno que est\u00e9. \u00bfQui\u00e9n me garantiza que no se ha escapado ning\u00fan pelillo en la depilaci\u00f3n integral a la que est\u00e1n obligados los modelos de semejante disciplina oriental? No. A m\u00ed no me encontrar\u00e9is ni de mesa ni de comensal. Me da cierto asquillo eso de comer directamente de los pectorales de un machote. Entendedme. Una cosa es estar ah\u00ed, a la faena, y otra es comer, comer, despu\u00e9s de rozarle el pezoncillo al chico y \u00a1delante de todo el mundo!<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">No he nacido yo para el nyotaimori; por mucho que me entrenasen. Se me pondr\u00eda la epidermis de punta al sentir el sashimi congelado encima del ombligo. Me ser\u00eda imposible permanecer impasible ante esa invasi\u00f3n de mi espacio personal. Qu\u00e9 quer\u00e9is que os diga: a lo mejor me sobra testosterona y eso de la territorialidad lo tengo muy presente; pero me imagino a Segismundo Lafuente acercar su bocaza, sus palillos, a semejante sitio y soy capaz de pegarle un mamporro. M\u00e1s que entrenamiento para ser modelo de body sushi necesitar\u00eda una sedaci\u00f3n nivel Profopol para soportar situaci\u00f3n semejante.<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\">Cada uno es libre de hacer con su cuerpo lo que quiera. Si alguien opta por prestar sus huesos y su carne para ser utilizada de semejante modo all\u00e1 \u00e9l o ella.\u00a0 Entiendo que esto es como lo de prestar el coche: una decisi\u00f3n arriesgada y personal.<\/span><\/p>\n<p><span style=\"color: #500050; font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Me parece desmesurado la que se ha montado en Castell\u00f3n porque el propietario de un restaurante quer\u00eda hacer sesiones de body sushi (que no deben superar m\u00e1s de las dos horas). Estoy en desacuerdo con dicho empresario que compara el nyotaimori o el nantamori (lo mismo, pero sobre cuerpo de var\u00f3n) con un espect\u00e1culo er\u00f3tico en vivo. La diferencia fundamental es aquello de la territorialidad. Las chicas o los chicos est\u00e1n en un escenario, a veces muy alto y siempre alejados. Luego est\u00e1n los seguratas, preparados para pararle los pies a cualquier entusiasta espont\u00e1neo.<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Adem\u00e1s, Imaginaos \u00a0la escena: diez machos alrededor de una hembra, casi piel con piel. Me da igual que la comida repose sobre una hoja de platanero o &#8211;espanto&#8211; envuelvan a la mesa humana en film transparente. Demasiada intimidad. Como la chica sea de poro abierto, fin del romanticismo. Como aquello se ponga caliente (en grados<\/span><span style=\"font-family: Verdana, sans-serif;\">\u00a0<\/span><em style=\"font-family: Verdana, sans-serif;\">Fahrenheit<\/em><span style=\"font-family: Verdana, sans-serif;\">\u00a0<\/span><span style=\"font-family: Verdana, sans-serif;\">-lo otro ni se contempla-) ya veo el sushi resbalar por la humedad reinante; a ellos, entre risas y cierta hambre, perseguir un maki con desesperaci\u00f3n porque ella estornuda o le entra la tiritona y aquello se mueve m\u00e1s que un postre de gelatina.<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Adoro la cultura japonesa y, por descontado, su comida. Cuentan que el nyotaimori hunde sus or\u00edgenes en la noche de los tiempos, en la \u00e9poca dorada de las Geishas; pero estoy segura que las que se prestaban a esto no eran las mejores, no aquellas cuyos servicios manten\u00edan la casa, esa especie de gineceo donde las mujeres se entrenaban para ser divinas y hermosas, cultas y sumisas pero con pocas tonter\u00edas.<\/span><\/p>\n<p><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Verdana, sans-serif;\">Los japoneses, que tienen m\u00e1quinas expendedoras con bragas usadas, que viven m\u00e1s de la fantas\u00eda que de realidades (llegan tan agotados a sus hogares que apenas hacen el amor); que son admirables en tantos \u00e1mbitos, permanecen a\u00fan en una cultura machista donde la mujer &#8211;real o personaje manga &#8212; brillar\u00e1, siempre y cuando se pliegue a los deseos de las fantas\u00edas masculinas.<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Me ser\u00eda imposible ser modelo de Body Sushi \u00a1Imaginaos qu\u00e9 cosquillas! Y, por favor, \u00a1Qu\u00e9 verg\u00fcenza! Todas las lorzas al aire y unos t\u00edos husme\u00e1ndome el sobaco. Horroroso, horroroso.\u00a0 Tampoco comer\u00eda sushi del cuerpo de un caballero, por bueno que est\u00e9. \u00bfQui\u00e9n me garantiza que no se ha escapado ning\u00fan pelillo en la depilaci\u00f3n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,24,57,101,121,122],"tags":[],"class_list":["post-373","post","type-post","status-publish","format-standard","hentry","category-alimentacion","category-belleza","category-estereotipos","category-mujer","category-punto-g","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}