{"id":385,"date":"2013-02-17T16:29:57","date_gmt":"2013-02-17T16:29:57","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=385"},"modified":"2013-02-17T16:29:57","modified_gmt":"2013-02-17T16:29:57","slug":"arquetipos-mafiosos-y-princesas-porque-nos-encanta-el-cotilleo","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/02\/17\/arquetipos-mafiosos-y-princesas-porque-nos-encanta-el-cotilleo\/","title":{"rendered":"Arquetipos, mafiosos y princesas (Porque nos encanta el cotilleo)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px;\">\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-ZEWxOXfnbqI\/USEDXuPKDVI\/AAAAAAAACNk\/aojzuDPt0KA\/s1600\/arquetipos.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-ZEWxOXfnbqI\/USEDXuPKDVI\/AAAAAAAACNk\/aojzuDPt0KA\/s1600\/arquetipos.jpg\" alt=\"\" width=\"240\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/p>\n<\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\"><br \/>\n<\/span><br \/>\n<span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">No busqu\u00e9is ficci\u00f3n en las teleseries. Est\u00e1n en las p\u00e1ginas de los peri\u00f3dicos. Cre\u00edamos que nuestro <strong>pa\u00eds<\/strong> era serio y resulta que es un cap\u00edtulo <strong>de<\/strong> <strong>Mortadelo y Filem\u00f3n<\/strong> con micros ocultos en los centros de mesa y qui\u00e9n sabe si en la merluza con salsa verde. Ni zapat\u00f3fono ni Ofelia. Aqu\u00ed tenemos ex-amantes aterradas que deciden acogerse al sagrado de los medios, como si los medios nos protegiesen de algo. Cierto: no me gustar\u00eda estar en su pellejo; pero, \u00bfa qu\u00e9 viene ahora este acto de contrici\u00f3n? Todo \u00a0recuerda a las vetustas estrategias de <strong>Hearst<\/strong>, el magnate del amarillismo para distraer la atenci\u00f3n de lo que realmente importa, una campa\u00f1a orquestada por alg\u00fan guionista maquiav\u00e9lico que consigue un sue\u00f1o casi imposible: tus personajes son pura realidad. <strong>&#8220;El cunnilingus y la psiquiatr\u00eda nos han llevado a esto&#8221;, que dir\u00eda Tony Soprano<\/strong>. Caemos como moscas en la red, enamorados de este rocambolesquismo de culebr\u00f3n, donde todo es real pero falso. O francamente falso, como escribi\u00f3 Truman <strong>Capote<\/strong>. Porque, se\u00f1oras y se\u00f1ores: <strong>nos encanta el cotilleo.<\/strong><\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">Confesad: \u00bfQui\u00e9n no se ha preguntado que hac\u00eda esa rubia tan fina con B\u00e1rcenas? Ella parece un anuncio de Tous: elegante, discreta y estilizada. Luce melena Pantene y tiene pinta de ser perfecta por todos sus costados, &#8220;because I&#8217;m worth it&#8221;(susurra escondida bajo su flequillo).<\/span><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\"><br \/>\n<\/span><\/p>\n<\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">A <strong>B\u00e1rcenas<\/strong> le pones un ch\u00e1ndal y es el t\u00edpico chulo poligonero con reloj de oro, medallones, camiseta imperio y puro sempiterno. Su asombroso parecido con <strong>Fat Tony<\/strong> (el mafioso de &#8220;Los Simpson&#8221;) ha ocasionado m\u00e1s de un comentario. Sus patillas, al estilo Pauli Gualtieri (&#8220;Los Soprano&#8221;) le confieren ese aire intimidatorio de ojo morado, color 500 euros. Yo me he contestado a esa pregunta: lo que hac\u00eda esa rubia con B\u00e1rcenas era vivir de puta madre. Tanto es as\u00ed que a ella ni le iban ni le ven\u00edan sus negocios. Yo creo a Rosal\u00eda Iglesias: \u00bfPara qu\u00e9 se iba a preocupar ella de esas frusler\u00edas? Estar guapa y radiante lleva mucho esfuerzo, sacrificio y tiempo.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">El caso de <strong>Mar\u00eda Victoria<\/strong> es diferente. Las amantes siempre llevan el peso de la culpa aunque no quieran. Por cultura, por gen\u00e9tica, estamos condenada a ser Mar\u00eda de la O &#8220;que desgrasiaita t\u00fa ereh teni\u00e9ndolo t\u00f3&#8221;. Es un c\u00edrculo vicioso y adictivo. T\u00fa mientes, me lo cuentas, te desahogas. Yo miento. Nos enga\u00f1amos, pero al final me libero y lo suelto todo delante de una c\u00e1mara. Dentro de nada, la tendremos en &#8220;S\u00e1lvame&#8221;. Consuelo Hormigos ya se ha ido a &#8220;Mira qui\u00e9n salta&#8221;. <strong>La cadena de culpabilidades al final desemboca en nosotros, p\u00fablico inepto que engulle lo que le echen<\/strong>. \u00bfPor qu\u00e9? <strong>Porque nos encanta el cotilleo<\/strong>. Y como la cotidianidad es muy aburrida, a ese caldo de desprop\u00f3sitos siempre se suma la ficci\u00f3n, que mezclada con la realidad hace un buen cocido. Las cosas como son.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">Cuando pase el tiempo, B\u00e1rcenas no ser\u00e1 ese tipo que llevaba una presunta contabilidad B del PP. No. Ser\u00e1 el arquetipo mafioso, chulesco que nos cautivar\u00e1 por su caradura inenarrable. Dentro de una d\u00e9cada, <strong>Undargarin <\/strong>vivir\u00e1 en otro pa\u00eds. Quiz\u00e1 siga con Cristina; pero en nuestro fuero interno ser\u00e1 el arquetipo del <strong>truh\u00e1n que desflor\u00f3 a la princesa<\/strong> (con su boca de fresa) y la hizo morder el polvo. Noveleros; que sois unos noveleros.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"background-color: white; color: #222222; font-size: 13px; text-align: justify;\"><span style=\"font-family: Trebuchet MS, sans-serif; font-size: 12pt; line-height: 18px;\">Y al final, todos se ir\u00e1n de rositas. Har\u00e1n suya otra famosa frase de Tony Soprano: &#8220;No pagar\u00e9. S\u00e9 demasiado sobre extorsi\u00f3n&#8221;. Pero la culpa es nuestra: porque <strong>nos encanta el cotilleo.<\/strong><\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; No busqu\u00e9is ficci\u00f3n en las teleseries. Est\u00e1n en las p\u00e1ginas de los peri\u00f3dicos. Cre\u00edamos que nuestro pa\u00eds era serio y resulta que es un cap\u00edtulo de Mortadelo y Filem\u00f3n con micros ocultos en los centros de mesa y qui\u00e9n sabe si en la merluza con salsa verde. Ni zapat\u00f3fono ni Ofelia. Aqu\u00ed tenemos ex-amantes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,37,57,84,86,89,100,115,121,122],"tags":[],"class_list":["post-385","post","type-post","status-publish","format-standard","hentry","category-cine","category-cuentos-de-hadas","category-estereotipos","category-literatura","category-los-soprano","category-mafiosos","category-mortadelo-y-filemon","category-parejas-de-cine","category-punto-g","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=385"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/385\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}