{"id":388,"date":"2013-02-17T21:28:36","date_gmt":"2013-02-17T21:28:36","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=388"},"modified":"2013-02-17T21:28:36","modified_gmt":"2013-02-17T21:28:36","slug":"la-filmoteca-y-esad-juntos-de-nuevo-para-la-fiesta-de-grease","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/02\/17\/la-filmoteca-y-esad-juntos-de-nuevo-para-la-fiesta-de-grease\/","title":{"rendered":"La filmoteca y ESAD juntos de nuevo para la fiesta de Grease"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/0pyA6jAM3_I\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<div class=\"MsoNormal\"><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">La Filmoteca Regional Francisco<br \/>\nRabal vuelve a colaborar con la ESAD (Escuela Superior de Arte Dram\u00e1tico) para<br \/>\nque la proyecci\u00f3n de GREASE en pantalla grande se convierta en un d\u00eda especial.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">El pr\u00f3ximo<strong> viernes 22 de febrero<\/strong> <strong>(21,00h)<\/strong> los alumnos de musical,<br \/>\ndirigidos por Raquel Jim\u00e9nez, interpretar\u00e1n en directo el n\u00famero final del<br \/>\nfamoso musical, titulado <em>We go together<\/em>, unos &#8220;teloneros&#8221; de excepci\u00f3n<br \/>\npara este filme, que acaba de cumplir 35 a\u00f1os. La Filmoteca repite la<br \/>\nexperiencia de West Side Story, dado el \u00e9xito cosechado el pasado mes de<br \/>\noctubre con la sala llena los dos d\u00edas de proyecci\u00f3n.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">Grease (1978) es una pel\u00edcula\u00a0musical ambientada en los a\u00f1os 50, dirigida por Randal Kleiser y protagonizada<br \/>\npor John Travolta, y Olivia Newton-John, basada en el musical hom\u00f3nimo de 1972,<br \/>\ncreado por Jim Jacobs y Warren Casey.<br \/>\nGrease fue la gran catapulta hacia el \u00e9xito de la actriz de origen<br \/>\naustraliano y, sobre todo, de Travolta. \u00a0<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">El musical cuenta la historia de\u00a0amor del rebelde Danny Zuko (John Travolta) y la inocente Sandy Olsson (Olivia<br \/>\nNewton-John). Ambos se conocen durante el verano y al despedirse ninguno de los\u00a0dos piensa en que se vayan a ver de nuevo. Pero se equivocaban: cuando ella decidematricularse en el mismo instituto que su amiga Frenchy (Didi Conn) lo \u00faltimo\u00a0que esperaba era convertirse en compa\u00f1era de Danny, el co-l\u00edder rebelde de los<br \/>\nT-Birds.<strong> El personaje de Sandy Olson (interpretado por Olivia Newton-John)\u00a0estaba basado en la actriz Sandra Dee y a su vez Rizzo (Stockard Channing) en\u00a0Marilyn Monroe.<\/strong><\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">Se sugiere a los asistentes\u00a0vestir con el look de la pel\u00edcula en la medida de lo posible. Imitar el atuendo<br \/>\nnegro total de Olivia Newton-John no es excesivamente complicado; al igual que\u00a0el estilo teenager de los chicos: bombers, vaqueros y zapatillas Old-Star.\u00a0 Este no es un requisito obligatorio pero\u00a0ayudar\u00eda a que la proyecci\u00f3n de Grease resulte una aut\u00e9ntica fiesta, a la\u00a0altura que merece un film que ha marcado a m\u00e1s de una generaci\u00f3n.<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: Verdana, sans-serif;\">Se puede reservar entrada (2,5 \u20ac) en los tel\u00e9fonos de la filmoteca 968 902201<\/span><\/div>\n<div class=\"MsoNormal\"><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La Filmoteca Regional Francisco Rabal vuelve a colaborar con la ESAD (Escuela Superior de Arte Dram\u00e1tico) para que la proyecci\u00f3n de GREASE en pantalla grande se convierta en un d\u00eda especial. El pr\u00f3ximo viernes 22 de febrero (21,00h) los alumnos de musical, dirigidos por Raquel Jim\u00e9nez, interpretar\u00e1n en directo el n\u00famero final del famoso musical, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133],"tags":[],"class_list":["post-388","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/388\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}