{"id":457,"date":"2013-05-26T16:03:07","date_gmt":"2013-05-26T16:03:07","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=457"},"modified":"2013-05-26T16:03:07","modified_gmt":"2013-05-26T16:03:07","slug":"desnudez-perversa","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/05\/26\/desnudez-perversa\/","title":{"rendered":"Desnudez perversa"},"content":{"rendered":"<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-Puk7jok9oRc\/UaIwVR3yVpI\/AAAAAAAACYg\/lc_C08az6bU\/s1600\/desnudez.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-Puk7jok9oRc\/UaIwVR3yVpI\/AAAAAAAACYg\/lc_C08az6bU\/s1600\/desnudez.jpg\" alt=\"\" width=\"240\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-8xb9CXGfy4k\/UaIxS0TP4UI\/AAAAAAAACYs\/kJNtVwezFDE\/s1600\/mercedes.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-8xb9CXGfy4k\/UaIxS0TP4UI\/AAAAAAAACYs\/kJNtVwezFDE\/s1600\/mercedes.jpg\" alt=\"\" width=\"320\" height=\"181\" border=\"0\" \/><\/a><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">Dios nos expuls\u00f3 del Para\u00edso. \u00a0Y entonces lleg\u00f3 la verg\u00fcenza, el pudor por la propia carne y los taparrabos. La culpa fue de la mujer, ya lo sab\u00e9is. Eva, que era muy picarona, incit\u00f3 a Ad\u00e1n a morder del fruto prohibido y un \u00e1ngel exterminador \u00a0alz\u00f3 su espada de fuego y los mand\u00f3 con viento fresco al mundo real. Y aqu\u00ed estamos. Jodidos desde entonces.<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">A veces pienso que quien escribi\u00f3 el Gen\u00e9sis ten\u00eda esp\u00edritu masoca. Vamos a ver, alma de c\u00e1ntaro <strong>\u00bfPara que cuelgan las manzanas de los \u00e1rboles si no es para com\u00e9rselas?. A veces pienso que quien escribi\u00f3 el G\u00e9nesis viv\u00eda resentido y abandonado por una mujer amante de las manzanas. A partir de entonces, todas somos malas<\/strong>. Todas somos sospechosas.\u00a0 No hay corriente anti -patriarcal capaz de levantar semejante losa.<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><strong>La cosa del taparrabos es un s\u00edmbolo de nuestra verg\u00fcenza. Todo lo que rodea los genitales est\u00e1 envuelto en el misterio y en bochorno<\/strong>. Me pregunto \u00bfPor qu\u00e9 algunos ni\u00f1os disfrutan mostrando la cuca? \u00bfPor qu\u00e9 algunas ni\u00f1as se levantan las faldas?\u00a0 Mostramos lo prohibido, lo pecaminoso. Estamos contaminados desde el vientre de nuestra madre.<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">Cada vez que a una modelo se le cae el vestido y ense\u00f1a los pechos por accidente se arma el esc\u00e1ndalo. S\u00f3lo son unos pechos. A veces los vemos sin pudor en las pasarelas. Quiz\u00e1 desde el front row, desde el ritmo atronador de los pases de moda, un pecho fuera es igual que un volante. O sea, un adorno. \u00a0Pero cuando se muestra una teta involuntariamente, ya tenemos a nuestro viejo dictador del G\u00e9neis, iracundo, con sus dedo acusador.\u00a0<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><strong>Merceditas Mil\u00e1 desvela la inenarrable imagen de sus bragas. No importa que sea las ant\u00edpodas del erotismo. Ah\u00ed tienes a todo el mundo, salivando<\/strong>, enganchados a la cutrevisi\u00f3n. Eva Longoria se pasea por la alfombra de\u00a0 Cannes, se remanga y, hala, habemus foto. \u00a1\u00a1Parece que no lleva la susodicha prenda \u00edntima y nos muestra un atisbo de susodicha parte!!. En las \u00faltimas horas varias conocidas han ense\u00f1ado parte\u00a0 de sus carnes.\u00a0 Incluso a la inefable Mariah Carey se le rompi\u00f3 el vestido. Igual que a Sof\u00eda Vergara. <strong>A salivar, est\u00fapidos<\/strong>. Porque verse, verse, no se ve nada. Pero caemos en la trampa y sus asesores de imagen se frotan las manos. Han conseguido lo que quer\u00edan.<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">No hay como ense\u00f1ar el chichi para provocar al personal. Pero hay que ense\u00f1arlo con tron\u00edo. No basta con hacer como Marta Ch\u00e1varri en su d\u00eda. Salir en plan comando es insuficiente. Lo hace Halle Berry cada dos por tres \u00bfQu\u00e9 quer\u00e9is que os diga? Ver aquello que me recuerda a un sobaco sudado. No me resulta excitante.<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">La desnudez propia y ajena es un foco de conflictos. <strong>\u00bfNunca hab\u00e9is tenido ese sue\u00f1o angustioso en el que andabais completamente desnudos por la calle y todo el mundo os miraba? \u00bfNo era espantoso?<\/strong>\u00a0 Lanzo la siguiente reflexi\u00f3n: \u00bfPor qu\u00e9 la desnudez genera esta controversia?. Despu\u00e9s de todo no es m\u00e1s que un trozo de nuestra carne. \u00bfPor qu\u00e9 la visi\u00f3n de los genitales nos descuadra sobremanera?. Y sobre todo, si<strong> Dios en su infinita sabidur\u00eda coloc\u00f3 los \u00f3rganos reproductivos ah\u00ed, tan cerca de los \u00f3rganos excretores (lo cual no deja de ser algo escatol\u00f3gico) \u00bfPor qu\u00e9 tanta imaginer\u00eda a su alrededor? \u00bfNo es una forma sabia de quitarles importancia?<\/strong><\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\"><br \/>\n<\/span><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-size: 12pt; line-height: 18px;\"><span style=\"font-family: Helvetica Neue, Arial, Helvetica, sans-serif;\">Si lo pens\u00e1is bien, andar como posesos buscando las desnudeces ajenas no deja de ser pat\u00e9tico. Y respecto a nuestros genitales, gozemos de ellos y acallemos el circo. De ah\u00ed venimos todos, as\u00ed que no deber\u00eda causarnos veg\u00fcenza.<\/span><\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Dios nos expuls\u00f3 del Para\u00edso. \u00a0Y entonces lleg\u00f3 la verg\u00fcenza, el pudor por la propia carne y los taparrabos. La culpa fue de la mujer, ya lo sab\u00e9is. Eva, que era muy picarona, incit\u00f3 a Ad\u00e1n a morder del fruto prohibido y un \u00e1ngel exterminador \u00a0alz\u00f3 su espada de fuego y los mand\u00f3 con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,24,57,58,101,121,122],"tags":[],"class_list":["post-457","post","type-post","status-publish","format-standard","hentry","category-articulos-de-opinion","category-belleza","category-estereotipos","category-exhibicionistas","category-mujer","category-punto-g","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/457\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}