{"id":458,"date":"2013-06-02T18:40:06","date_gmt":"2013-06-02T18:40:06","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=458"},"modified":"2013-06-02T18:40:06","modified_gmt":"2013-06-02T18:40:06","slug":"sigue-el-camino-del-orgasmo","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/06\/02\/sigue-el-camino-del-orgasmo\/","title":{"rendered":"Sigue el camino del orgasmo"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/2.bp.blogspot.com\/-md0vRmnH6PA\/UauNYCU0TJI\/AAAAAAAACZ8\/eCRVLLpiWRw\/s1600\/paul-walker-20070314-225968.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"320\" src=\"\/\/2.bp.blogspot.com\/-md0vRmnH6PA\/UauNYCU0TJI\/AAAAAAAACZ8\/eCRVLLpiWRw\/s320\/paul-walker-20070314-225968.jpg\" width=\"219\" \/><\/a><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px; text-align: center;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px; text-align: center;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px; text-align: center;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px; text-align: center;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px; text-align: center;\">\n<span style=\"font-family: Verdana, sans-serif;\">\u00bf<\/span><b style=\"font-family: Verdana, sans-serif;\">No es mucho m\u00e1s cruel acostarte con el leg\u00edtimo y fantasear con Paul Walker?<\/b><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">Mi amiga tiene un dilema. <b>Su marido le ha propuesto hacer un tr\u00edo.&nbsp; Nada de mont\u00e1rselo con otra. Lo que quiere \u00e9l es contratar a un puto para jugar en compa\u00f1\u00eda<\/b>. Ella se lo est\u00e1 pensando.&nbsp;<\/span><span style=\"font-family: Verdana, sans-serif;\">Los hay por 100 euros y &#8220;prometen aguantar toda una hora, ah\u00ed, dale que te pego, sin parar&#8221;, puntaliza &#8220;S&#8221; (la llamaremos as\u00ed). Ella, que est\u00e1 enamorada de&#8221; P&#8221; desde el primer d\u00eda, que jam\u00e1s le ha sido infiel, recibe esta ins\u00f3lita proposici\u00f3n indecente. \u00bfQu\u00e9 le puedo decir? Nunca se me ha planteado situaci\u00f3n semejante. Nunca he concebido la relaci\u00f3n amorosa fuera de un entorno de exclusividad y complicidad con s\u00f3lo una persona. Pero&#8230;Nunca se sabe. La vida es muy larga, da mucha vueltas, nos centrifuga, nos hace un gui\u00f1apo y cualquier d\u00eda va tu pareja y te suelta: <b>&#8220;quiero verte hacer el amor con otro hombre que no sea yo&#8221;.<\/b><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">\u00bfAlgo as\u00ed puede ser considerado una infidelidad? Pues depende. &#8220;Imagina&#8211;elucubra mi amiga&#8211; que a m\u00ed me gusta m\u00e1s con el puto que con \u00e9l \u00bfEntonces qu\u00e9? \u00bfY si a partir de ese momento descubro otras cosas y empiezo a buscarlas fuera de mi pareja? Complicada cuesti\u00f3n.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><b><br \/><\/b><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><b>Seg\u00fan me explicaba el otro d\u00eda el psicoanalista Pablo Juan Maestro, la infidelidad, como su propio nombre indica, significa falta de fe<\/b>. La pareja se rige por pactos y contratos. Si dentro de la pareja se admite una tercera, cuarta o quinta persona (o alguna m\u00e1s, aunque esto s\u00ed que me parecer\u00eda una multitud) nada que objetar. La gran traici\u00f3n es cuando se pierde la fe en la otra persona, en el proyecto en com\u00fan. Cuando aparecen los enamoramientos acalorados y cuando se pasan de las palabras a los hechos, entonces encontramos un camino sin retorno.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><b>\u00bfAlguien sabe calibrar las consecuencias de introducir un tercer elemento en una relaci\u00f3n de pareja?<\/b> Habr\u00e1 personas que se lo tomen como un juego m\u00e1s, lo cual no deja de parecerme una <b>cosificaci\u00f3n del g\u00e9nero humano. Toda prostituci\u00f3n lo es<\/b>. Compras carne, compras servicios sexuales (no me parece ni bien ni mal pero la cosa es as\u00ed, no me lo pod\u00e9is negar)&#8230;Pero \u00bfY si ocurre&nbsp; como barrunta &#8220;S&#8221;? \u00bfY si a partir del tr\u00edo, &#8220;P&#8221; empieza a no estar a la altura?. Ya lo sab\u00e9is, las comparaciones son odiosas. Un conocido m\u00edo practic\u00f3 un tr\u00edo y sali\u00f3 trasquilado. Fin de los experimentos. &#8220;Las cosas de comer y de montar no se dejan&#8221;, repet\u00eda siempre. Nunca m\u00e1s, repet\u00eda siempre, dolido, consternado, sumido en la estupefacci\u00f3n.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">Como soy muy desconfiada&nbsp; le digo a &#8220;S&#8221;: &#8220;\u00bfY si lo que quiere tu marido es un tr\u00edo con otra chica y te concede la gracia de ser la estrella invitada por una vez?&#8221;<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">&#8211;Ah no, de t\u00edas nada&#8211; &nbsp;concluye tajante.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><br \/><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">\u00bfQu\u00e9 aconsejar? Veamos, querida &#8220;S&#8221;, si te atreves, adelante. En el resto de casos, soy de la siguiente opini\u00f3n: &nbsp;si a una le gusta mucho un tipo y tiene pensamientos libidinosos con \u00e9l ya est\u00e1 pecando, pero de omisi\u00f3n, porque uno tiene que ser fiel a s\u00ed mismo en todo momento. \u00bfDe qu\u00e9 te sirve so\u00f1ar con el vecino del 5, pongamos por caso, y no llevarlo a la pr\u00e1ctica? \u00bf<b>No es mucho m\u00e1s cruel acostarte con el leg\u00edtimo y fantasear con Paul Walker? (en qu\u00e9 estar\u00e9 pensando, v\u00e1lgame) \u00bfNo es eso tambi\u00e9n una cosificaci\u00f3n de tu santo para montarte una fiesta privada donde ni siquiera \u00e9l est\u00e1 invitado?<\/b><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\"><b><br \/><\/b><\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\">\n<span style=\"font-family: Verdana, sans-serif;\">Ante la duda, lo tengo claro: &#8220;sigue el camino del orgasmo&#8221; como recomienda la psic\u00f3loga a su paciente&nbsp; en el corto titulado&nbsp;<i>Mujeres infieles<\/i>. Pinchad <a href=\"http:\/\/www.youtube.com\/watch?v=fwRvhEyAnRE\">aqu\u00ed<\/a> y me cont\u00e1is.<\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfNo es mucho m\u00e1s cruel acostarte con el leg\u00edtimo y fantasear con Paul Walker? Mi amiga tiene un dilema. Su marido le ha propuesto hacer un tr\u00edo.&nbsp; Nada de mont\u00e1rselo con otra. Lo que quiere \u00e9l es contratar a un puto para jugar en compa\u00f1\u00eda. Ella se lo est\u00e1 pensando.&nbsp;Los hay por 100 euros y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,20,121,122,131],"tags":[],"class_list":["post-458","post","type-post","status-publish","format-standard","hentry","category-apuntes-personales","category-articulos-de-opinion","category-punto-g","category-puntog","category-sexo"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}