{"id":509,"date":"2013-09-22T18:55:14","date_gmt":"2013-09-22T18:55:14","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=509"},"modified":"2013-09-22T18:55:14","modified_gmt":"2013-09-22T18:55:14","slug":"escuela-de-calor","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/09\/22\/escuela-de-calor\/","title":{"rendered":"Escuela de calor"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-igDLrmTlKRI\/Uj87eA9-N5I\/AAAAAAAAClI\/VXh1pmdyWXo\/s1600\/mujer_hombre_beso_mojado.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/2.bp.blogspot.com\/-igDLrmTlKRI\/Uj87eA9-N5I\/AAAAAAAAClI\/VXh1pmdyWXo\/s320\/mujer_hombre_beso_mojado.jpg\" alt=\"\" width=\"320\" height=\"240\" border=\"0\" \/><\/a><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-p2iAEkQzPSU\/Uj86dIhqkfI\/AAAAAAAAClA\/PCtWTHk3h50\/s1600\/escuelacalor.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/2.bp.blogspot.com\/-p2iAEkQzPSU\/Uj86dIhqkfI\/AAAAAAAAClA\/PCtWTHk3h50\/s320\/escuelacalor.jpg\" alt=\"\" width=\"240\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">No tengo nada en contra de los negocios legales, que conste, pero entre <strong><a href=\"http:\/\/www.andalucesdiario.es\/multimedia\/dos-hermanas-exporta-vaginas-a-toda-europa\/\">los hombres que meten su pene en vaginas de pl\u00e1stico <\/a><\/strong>y mujeres que aprenden la t\u00e9cnica de la felaci\u00f3n con pitos de pl\u00e1stico, olvidaremos la textura, el tacto, el sabor y olor del sexo de verdad. Se avecina el fin de los tiempos. Ni pensar quiero en las visiones de Nostradamus. L\u00e1stima de profeta, debi\u00f3 volverse loco al echar un vistazo a nuestra \u00e9poca. Pl\u00e1stico para evitar embarazos y pl\u00e1stico para sustituir a la carne de verdad. \u00a0Este no es el siglo XXI sino el siglo del Pexigl\u00e1s.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Para los que no se han enterado les cuento que <strong><a href=\"http:\/\/www.laverdad.es\/murcia\/rc\/20130920\/sociedad\/abren-primera-escuela-para-201309200056.html\">una se\u00f1ora de Rusia, Yekaterina Lyubimov, dice que en tres horas y media te ense\u00f1a hasta 50 t\u00e9cnicas de estimulaci\u00f3n del pene y por el m\u00f3dico precio de 75 euros<\/a><\/strong>.\u00a0<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Ya me imagino la conversaci\u00f3n: &#8220;pues se la com\u00ed a mi Sergi despu\u00e9s de morder ra\u00edz de genjibre&#8221;<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">-\u00bfY?<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">-Casi se la arranco de un mordisco porque dijo que le quemaba.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">-Yo prob\u00e9 la pasta de dientes con Mijail. Un desastre.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">&#8211; Tampoco me funcionar\u00e1. Nada, que no sacamos a nuestros chicos de un franc\u00e9s tradicional.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Mi pregunta es \u00bfPor qu\u00e9 hay una escuela para que las mujeres aprendan t\u00e9cnicas de sexo oral y no existe id\u00e9ntica formaci\u00f3n para los hombres? \u00a0Y me respondo con otra pregunta <strong>\u00bfOs imagin\u00e1is a los hombres reconociendo p\u00fablicamente su ineptitud para con el sexo opuesto?<\/strong> Me consta que todos dudamos. Incluso que ellos tambi\u00e9n dudan mucho. Todo el tiempo.<strong> Les obsesiona si nos gust\u00f3 la \u00faltima vez. Si son mejores amantes que sus predecesores, si la tienen m\u00e1s larga, m\u00e1s corta, m\u00e1s fina. Pero una cosa son sus dudas y otra muy distinta su amor propio y debilidades tendidas en un aula<\/strong>, compartidas por otros machos de su especie. \u00a0He de a\u00f1adir que yo tampoco me veo en la misma habitaci\u00f3n con un mont\u00f3n de chicas chupando con un &#8220;palo&#8221; de pl\u00e1stico.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">A la presi\u00f3n social que sufre la mujer por ser la m\u00e1s bella y la m\u00e1s flaca, se suma otra: hemos de ser las mejores amantes. Sospecho que, en alg\u00fan caso, la maestr\u00eda en t\u00e9cnicas masturbatorias puede ser un plus para cazar marido y este sea el objetivo real de tales escuelas pero consuela saber que en este campo todos estamos igual de indefensos e ignorantes \u00bfPor qu\u00e9? Porque el sexo nunca es igual. Cambian las condiciones, la hora del d\u00eda, la pareja, el momento, la edad. Es absurdo este af\u00e1n por controlar \u00a0todas las variables y factores de una cita amorosa.<strong> El sexo no es meteorolog\u00eda<\/strong>. Aunque ya os gustar\u00eda a muchos.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Miedosos del mundo, desde aqu\u00ed os lo digo: en el sexo siempre se es vulnerable pero por eso es tan irrepetibe y bonito.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Un amigo fue hace poco al doctor y le dijo que ten\u00eda que darle m\u00e1s al triki y menos a la cabeza. &#8220;Eres muy mono, est\u00e1s soltero, no s\u00e9 qu\u00e9 problema tienes&#8221;&#8211;le amonest\u00e9&#8211;<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">-Pues no es tan f\u00e1cil. Es que te habit\u00faas a esto de las redes sociales y, claro,\u00a1\u00a1es que es tan c\u00f3modo!!<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">\u00bfResultado? mi amigo, en la flor de la vida, acabar\u00e1 &#8211;si no sucede un milagro&#8211; consol\u00e1ndose con un pl\u00e1stico o acostumbr\u00e1ndose a esta tonter\u00eda de ponerse calentorro v\u00eda whatsapp para consumar el acto en solitario, en la frialdad de los azulejos de un cuarto de ba\u00f1o \u00bfNo es terrible?<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><strong>Existen muchas amenazas para disfrutar del sexo: las ETS, los embarazos no deseados pero la mayor amenaza es nuestro miedo a romper el caparaz\u00f3n y ser vulnerables frente al otro.<\/strong><\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No tengo nada en contra de los negocios legales, que conste, pero entre los hombres que meten su pene en vaginas de pl\u00e1stico y mujeres que aprenden la t\u00e9cnica de la felaci\u00f3n con pitos de pl\u00e1stico, olvidaremos la textura, el tacto, el sabor y olor del sexo de verdad. Se avecina el fin de los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57,121,122,124,131],"tags":[],"class_list":["post-509","post","type-post","status-publish","format-standard","hentry","category-estereotipos","category-punto-g","category-puntog","category-redes-sociales","category-sexo"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}