{"id":513,"date":"2013-10-06T16:32:24","date_gmt":"2013-10-06T16:32:24","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=513"},"modified":"2013-10-06T16:32:24","modified_gmt":"2013-10-06T16:32:24","slug":"el-porno-o-la-vida","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/10\/06\/el-porno-o-la-vida\/","title":{"rendered":"El porno o la vida"},"content":{"rendered":"<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-DKsBRi1uJLc\/UlGP_Q1-h6I\/AAAAAAAACoo\/NhqdtJT08cw\/s1600\/pornovida.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/4.bp.blogspot.com\/-DKsBRi1uJLc\/UlGP_Q1-h6I\/AAAAAAAACoo\/NhqdtJT08cw\/s320\/pornovida.jpg\" alt=\"\" width=\"240\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><\/div>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/-WvrJzwIgVd4\/UlGPRsC8fTI\/AAAAAAAACog\/iTGY7vK-x1U\/s1600\/sara.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/3.bp.blogspot.com\/-WvrJzwIgVd4\/UlGPRsC8fTI\/AAAAAAAACog\/iTGY7vK-x1U\/s320\/sara.jpg\" alt=\"\" width=\"245\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Todo empez\u00f3 el d\u00eda que <a href=\"http:\/\/www.huffingtonpost.es\/maximo-pradera\/\"><strong>Max Pradera<\/strong> <\/a>me sugiri\u00f3: &#8220;deber\u00edas escribir un art\u00edculo sobre <strong>esas personas que intentan imitar todo lo que ven en las pelis porno<\/strong>&#8220;. \u00a0Me vino inmediatamente a la cabeza esta frase \u00a0hecha: &#8220;El porno ha hecho mucho da\u00f1o&#8221; y una pregunta: &#8220;\u00bfDe verdad?&#8221; Creo que esta aseveraci\u00f3n carece de fundamento, a no ser que uno sea incapaz de distinguir realidad de ficci\u00f3n. Es m\u00e1s, <a href=\"http:\/\/www.mahernandez.es\/\">Miguel \u00c1ngel Hern\u00e1ndez<\/a>, sostiene <strong>que la pareja que ve porno unida, permanece unida<\/strong>. A pesar de que las comparaciones sean odiosas y a pesar de que el porno est\u00e1 dirigido, b\u00e1sicamente, al p\u00fablico masculino (films de <strong><a href=\"http:\/\/vimeo.com\/erikalust\">Erika Lust<\/a><\/strong>, aparte).\u00a0 Este producto, salvo excepciones &#8211;y no se me ofendan los se\u00f1ores&#8211; suele ser obsceno y denigrante para la mujer que, \u00faltimamente siempre acaba ba\u00f1ada por el semen del macho con cara de haberles tocado el premio gordo de loter\u00eda. Un horror.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><strong>Las pelis de hoy son b\u00e1sicamente escenas: planos, contraplanos\u00a0 y planos detalle. No hay argumento, nudo y desenlace, s\u00f3lo un escenario y fantas\u00edas<\/strong>. Recuerdo la primera vez que un viejo amigo (amante muy experimentado, por cierto) se sorprendi\u00f3 porque una chica le pidi\u00f3 que le diese cachetazos en el culo. A\u00fan no se hab\u00eda enterado de la existencia de a <strong>Grey<\/strong>, que, dicho sea de paso, tampoco es la vida &#8211;por suerte &#8212; porque \u00e9sta se escribe incluso mejor que la farragosa y repetitiva novela.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Realidad y ficci\u00f3n son \u00e1mbitos diferentes. El otro d\u00eda entramos en un ascensor<strong> Enrique Ujald\u00f3n, Antonio Rovira, <a href=\"http:\/\/www.arcadiespada.es\/\">Arcadi Espada<\/a>, Pepa Plaza <\/strong>y servidora (no pens\u00e9is cosas raras, acababa de terminar la charla e Arcadi) y lo solt\u00e9 en voz alta.&#8221; Ni loca me monto una escena de ascensor con estos calores y con mi claustrofobia&#8221;<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">&#8211;Sobre todo porque \u00a0aqu\u00ed no hay pisos altos &#8211;sucribi\u00f3 \u00a0sabiamente Rovira.\u00a0<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Y es que <strong>los mitos se derrumban como una monta\u00f1a de az\u00facar en el viento<\/strong>. En el porno todo es brutalidad, s\u00faper miembros, coitos de media hora, salvajes embestidas y cuerpos perfectos. &#8220;No sab\u00e9is c\u00f3mo os entiendo, porque adem\u00e1s de todo eso ten\u00e9is que competir con un mercado de potent\u00edsimos vibradores&#8221;, a\u00f1ad\u00ed. Hubo carcajadas, s\u00ed ,pero \u00bfMe falta raz\u00f3n?. Por eso aprecio y valoro al g\u00e9nero masculino. No porque se\u00e1is mi materia prima, como dec\u00eda Arcadi, sino porque <strong>si a nosotras la sociedad nos obliga a ser Barbies, lo vuestro creo que a veces es peor<\/strong>.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Por suerte, la vida es m\u00e1s simple que todo eso. Cierto que hay maravillosas escenas de amor que todas hemos so\u00f1ado vivir como las de\u00a0<em><a href=\"http:\/\/www.youtube.com\/watch?v=PeDNWyTmrgY\">El Paciente ingl\u00e9s<\/a><\/em>, o\u00a0<em>Infiel;<\/em>\u00a0\u00a0el acto arrebatado de Vincent Mart\u00ednez con Deneuve\u00a0<em>en <a href=\"http:\/\/www.youtube.com\/watch?v=l5Cb44ww_DQ\">Indochina<\/a><\/em>, o la desatada pasi\u00f3n de Irons en todos sus roles amorosos:\u00a0<em>Lolita<\/em>,\u00a0<em><a href=\"http:\/\/www.youtube.com\/watch?v=p1Na1m0qWc8\">Herida<\/a><\/em>\u00a0e incluso\u00a0<em>Madame Bovary<\/em>. Pero tambi\u00e9n es cierto que <strong>hombres y mujeres pueden repasar mentalmente hermosos escenarios, t\u00f3rridos besos y caricias de alto voltaje grabadas para siempre en la piel y el coraz\u00f3n<\/strong>. A un espectador de peli porno le aburrir\u00edan, claro, pero \u00bfQu\u00e9 criterio sentimental, amoroso y er\u00f3tico puede tener alguien que ve s\u00f3lo y exclusivamente porno?<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">Hacer el amor en una escalera de m\u00e1rmol de un palacio veneciano tiene sin duda un valor est\u00e9tico. Igual que el famoso sexo en la playa, en un campo de trigo bajo la lluvia (<em>Macht Point)<\/em>; o de pie, junto al pasamanos de una entrada al metro (<em>Nueve semanas y media)<\/em>. Pero <strong>las escaleras se te clavan, la arena pica, el trigo produce estornudos y el metro huele fatal. Y es una suerte porque la vida es as\u00ed de rica. Mucho mejor que el porno. D\u00f3nde va parar<\/strong>.<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\"><br \/>\n<\/span><\/div>\n<div style=\"background-color: white; color: #222222; font-size: 13px;\"><span style=\"font-family: Verdana, sans-serif;\">La foto es de Sara Saudkova<\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Todo empez\u00f3 el d\u00eda que Max Pradera me sugiri\u00f3: &#8220;deber\u00edas escribir un art\u00edculo sobre esas personas que intentan imitar todo lo que ven en las pelis porno&#8220;. \u00a0Me vino inmediatamente a la cabeza esta frase \u00a0hecha: &#8220;El porno ha hecho mucho da\u00f1o&#8221; y una pregunta: &#8220;\u00bfDe verdad?&#8221; Creo que esta aseveraci\u00f3n carece de fundamento, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121,122,131],"tags":[],"class_list":["post-513","post","type-post","status-publish","format-standard","hentry","category-punto-g","category-puntog","category-sexo"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}