{"id":548,"date":"2013-12-19T10:16:51","date_gmt":"2013-12-19T10:16:51","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=548"},"modified":"2013-12-19T10:16:51","modified_gmt":"2013-12-19T10:16:51","slug":"iluminados","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2013\/12\/19\/iluminados\/","title":{"rendered":"Iluminados"},"content":{"rendered":"<p><a href=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2013\/12\/bombilla-de-clip-art_424936.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-549\" title=\"bombilla-de-clip-art_424936\" src=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2013\/12\/bombilla-de-clip-art_424936.jpg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2013\/12\/bombilla-de-clip-art_424936.jpg 623w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2013\/12\/bombilla-de-clip-art_424936-150x150.jpg 150w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>D\u00e9ficit tarifario es el nuevo palabro que se han inventado los pol\u00edticos para hacernos pasar de nuevo por el aro. Se anuncia una subida del 11% del recibo de la luz para el pr\u00f3ximo 2014. Bonita forma de darnos las pascuas.<br \/>\nLa liberalizaci\u00f3n de la energ\u00eda pens\u00e1bamos que nos iba a traer a empresas m\u00e1s competitivas, que pujar\u00edan porque nosotros, los consumidores, apost\u00e1semos por un servicio u otro. Pero no. Lo que sucede es que nos llegan unos facturones imponentes y p\u00f3ngase usted a reclamar. Y el coste de las facturas sube y sube hasta el infinito y m\u00e1s all\u00e1.<\/p>\n<p>\u00bfPor qu\u00e9 sucede esto? \u00bfQui\u00e9n decide, qui\u00e9n analiza, qui\u00e9n sentencia que producir electricidad en nuestro pa\u00eds es m\u00e1s caro en el resto de Europa? \u00bfEs por las prebendas que tenemos que abonar a los ex-altos cargos, cuyas carreras profesionales son aparcadas en estos cementerios de elefantes donde por rascarse los hue&#8230;, digo, la cabeza, les pagan unos sueldos de seis ceros? \u00bfEs porque en nuestro pa\u00eds no hay tantas nucleares como en otros lugares? \u00bfEs porque nos falta energ\u00eda y se la tenemos que comprar a Francia al precio que ellos nos pongan? \u00bfEs porque nos toca a todos sufragar empresas e industrias deficitarias?<\/p>\n<p>Yo no tengo las respuestas, por desgracia. Si hay un experto energ\u00e9tico en la sala, que se manifieste y ponga algo de luz, valga la redundancia, en esta cuesti\u00f3n.<\/p>\n<p>Lo \u00fanico que s\u00e9, que sabemos, es que los sueldos son cada vez m\u00e1s bajos, los trabajos m\u00e1s precarios, los servicios sociales son menos servicios y menos sociales y que pagamos la energ\u00eda, tanto el combustible como la el\u00e9ctrica, a precios desorbitados.<\/p>\n<p>Si hay familias que viven con sueldos de 800 euros \u00bfMe pueden explicar ustedes a mi c\u00f3mo les va a dar para vivir, pagar todos los impuestos que a las autoridades se les ocurran y estar al d\u00eda con los recibos? \u00bfQu\u00e9 queda para comer? \u00bfQu\u00e9 queda para otras cosas fundamentales como vivir, salir a tomar una ca\u00f1a con los amigos o ir un par de veces al a\u00f1o al cine?<\/p>\n<p>\u00bfPor qu\u00e9 este pa\u00eds vive un NEOFEUDALISMO donde s\u00f3lo sobreviven los enchufados, hijos de enchufados y la mediocridad?<\/p>\n<p>Lo que es incre\u00edble es que todav\u00eda mantengamos el humor, las ganas de pelear, el tes\u00f3n, la simpat\u00eda y el riesgo que supone apostar por este futuro cada vez m\u00e1s incierto.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; D\u00e9ficit tarifario es el nuevo palabro que se han inventado los pol\u00edticos para hacernos pasar de nuevo por el aro. Se anuncia una subida del 11% del recibo de la luz para el pr\u00f3ximo 2014. Bonita forma de darnos las pascuas. La liberalizaci\u00f3n de la energ\u00eda pens\u00e1bamos que nos iba a traer a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-548","post","type-post","status-publish","format-standard","hentry","category-energia"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}