{"id":575,"date":"2014-02-14T13:40:59","date_gmt":"2014-02-14T13:40:59","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=575"},"modified":"2014-02-14T13:40:59","modified_gmt":"2014-02-14T13:40:59","slug":"el-sexting-ya-no-es-cool","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2014\/02\/14\/el-sexting-ya-no-es-cool\/","title":{"rendered":"El sexting ya no es cool"},"content":{"rendered":"<div class=\"MsoNormal\"><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-KqdO2y78Lp4\/Uve7IWj96uI\/AAAAAAAAC8U\/99oFQrLLdDQ\/s1600\/sexting.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/4.bp.blogspot.com\/-KqdO2y78Lp4\/Uve7IWj96uI\/AAAAAAAAC8U\/99oFQrLLdDQ\/s1600\/sexting.jpg\" alt=\"\" width=\"240\" height=\"320\" border=\"0\" \/><\/a><\/span><\/div>\n<p>&nbsp;<\/p>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">La historia es sencilla.<br \/>\nCuando uno se enamora hace tonter\u00edas. Empieza con un &#8220;<strong>cu\u00e9ntame qu\u00e9<br \/>\nme har\u00e1s cuando nos veamos&#8221;<\/strong> y termina con el primer plano de unos<br \/>\ngenitales. La cosa tiene ya poco de novedoso<br \/>\ncuando<strong> las starletts del momento se despiden de sus seguidores en<br \/>\nTwitter con un buenas noches y autofoto de ellas medio en pelotas<\/strong> para<br \/>\ndemostrarnos, imagino, lo buenas que est\u00e1n o para conseguir 140.000 likes de<br \/>\ngolpe. <\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">Creo que el sexting est\u00e1 empezando a perder gracia; que dej\u00f3<br \/>\nde ser cool hace unos cuantos meses y vistos los problemas posteriores que<br \/>\nacarrea, buscar\u00eda otros m\u00e9todos de acercamiento er\u00f3tico-amorosos m\u00e1s pr\u00e1cticos.<br \/>\n<strong>El t\u00e9rmino comenz\u00f3 a popularizarse nada menos que en 2005<\/strong> en los pa\u00edses<br \/>\nanglosajones y en 2008 una encuesta norteamericana (The national campaing to<br \/>\nprevent teen and unplanned pregnancy) revel\u00f3 que el 20% de j\u00f3venes entre 13 y<br \/>\n19 a\u00f1os reconoc\u00eda haber enviado y colgado fotos en las que aparec\u00edan<br \/>\nsemidesnudos. Otra encuesta posterior revelaba que de forma habitual estas<br \/>\nfotos se enviaban a conocidos pero un <strong>11% confesaba haberlas mandado a personas<br \/>\nque jam\u00e1s hab\u00edan visto. La temeridad adolescente,supongo<\/strong>.<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">El profesor de<br \/>\nCriminolog\u00eda y Derecho Penal de la Universidad Internacional de<br \/>\nCatalu\u00f1a, <strong>Jos\u00e9 R. Agustina<\/strong> explica que legalmente se reacciona ante el sexting<br \/>\nen un doble sentido: por un lado, para <strong>evitar la producci\u00f3n de pornograf\u00eda<br \/>\ninfantil por cauces que no son los habituales, en los que la iniciativa del<br \/>\nmenor no se ve afectada por los adultos y, por otro, para proteger la<br \/>\ndeficiente autodeterminaci\u00f3n sexual de los menores<\/strong>. Hay que subrayar que la<br \/>\nmayor\u00eda de los pa\u00edses \u00e9stos carecen de ella. Es decir, el menor no tiene<br \/>\nlibertad sexual. Sin embargo, <strong>en Espa\u00f1a m\u00e1s del 68% de los j\u00f3venes entre 10 y<br \/>\n15 a\u00f1os s\u00ed tiene un m\u00f3vil<\/strong>. Qu\u00e9 dif\u00edcil poner puertas al campo cuando hay tantas<br \/>\nv\u00edas de intercambio de im\u00e1genes y palabras.<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">La aplicaci\u00f3n de moda entre los j\u00f3venes es el <strong>snapchat<\/strong>, el<br \/>\nequivalente a &#8220;este mensaje se autodestruir\u00e1&#8221;. Intercambio de<br \/>\ncontenidos de alto voltaje que no dejan huella. Salvo que alguien sea lo<br \/>\nbastante r\u00e1pido para hacer una captura de pantalla. El <strong>chatroulette<\/strong> te permite<br \/>\ntener sexo virtual con personas de todo el mundo. Es expl\u00edcito a m\u00e1s no poder. Hay<br \/>\notras aplicaciones como el <strong>Tinder,<\/strong> muy similar y <strong>myLol<\/strong>, una red social de ligue<br \/>\npara teenagers.<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">El sexting abre la puerta al ciberbullying. O sea, al acoso<br \/>\ntel\u00e9fonico, pero lo peor de todo es que es la propia v\u00edctima quien propicia<br \/>\neste acoso enviando fotos expl\u00edcitas. Lo que viene despu\u00e9s es previsible:<br \/>\n<strong>&#8220;rompes conmigo y toda la escuela ver\u00e1 tus tetas&#8221;<\/strong>. Los adultos<br \/>\ntambi\u00e9n se dejan llevar por estas deleznables conductas (la venganza del reenv\u00edo masivo de im\u00e1genes \u00edntimas), incluso se valen de<br \/>\nlas redes para acceder a los m\u00e1s j\u00f3venes (grooming).<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\">Las consecuencias del sexting han sido terribles en algunos<br \/>\ncasos. <strong>Vanessa Hudgens<\/strong> es una joven a la que sus padres compran un m\u00f3vil, ella env\u00eda<br \/>\nfotos expl\u00edcitas a su novio y meses despu\u00e9s rompe con \u00e9l. Ah\u00ed comienza la<br \/>\npesadilla, llegando al absurdo de que Vanessa no s\u00f3lo <strong>sufri\u00f3 la verg\u00fcenza de<br \/>\nser la comidilla de su escuela, sino que acab\u00f3 siendo condenada por\u00a0 producir, distribuir y poseer pornograf\u00eda<br \/>\ninfantil<\/strong>. El caso de Jesse <strong>Logan <\/strong>termin\u00f3 con su suicidio (Cincinnati, 2009).<\/span><\/div>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><br \/>\n<\/span><\/div>\n<p>&nbsp;<\/p>\n<div class=\"MsoNormal\"><span style=\"font-family: Trebuchet MS, sans-serif;\"><strong>La tonter\u00eda de hacernos fotos a cada rato est\u00e1 llegando<br \/>\ndemasiado lejos. Me aburre. El sexting, que tambi\u00e9n practican muchos adultos<\/strong><br \/>\n(m\u00e1s del 50% son mayores de 18 a\u00f1os, seg\u00fan Mac Afee) tiene sentido si tu pareja<br \/>\nest\u00e1 lejos, o para reavivar la llama. El resto es un perder el tiempo peligroso<br \/>\nporque <strong>nunca, nunca sabes donde acabar\u00e1 tu selfie.\u00a0<\/strong><\/span><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; La historia es sencilla. Cuando uno se enamora hace tonter\u00edas. Empieza con un &#8220;cu\u00e9ntame qu\u00e9 me har\u00e1s cuando nos veamos&#8221; y termina con el primer plano de unos genitales. La cosa tiene ya poco de novedoso cuando las starletts del momento se despiden de sus seguidores en Twitter con un buenas noches y autofoto [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[],"class_list":["post-575","post","type-post","status-publish","format-standard","hentry","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}