{"id":618,"date":"2014-06-30T07:15:19","date_gmt":"2014-06-30T07:15:19","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=618"},"modified":"2014-06-30T07:15:19","modified_gmt":"2014-06-30T07:15:19","slug":"ana-maria-matute-o-el-arte-de-sonar","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2014\/06\/30\/ana-maria-matute-o-el-arte-de-sonar\/","title":{"rendered":"Ana Mar\u00eda Matute o el arte de so\u00f1ar"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/06\/Lola-y-Matute.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-619\" title=\"Lola y Matute\" src=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/06\/Lola-y-Matute.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/06\/Lola-y-Matute.jpg 400w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/06\/Lola-y-Matute-300x225.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\u00a0Con Ana Mar\u00eda Matute en la Biblioteca Salvador Garc\u00eda Aguilar de Molilna de Segura \u00a0en el primer a\u00f1o de Escritores en su tinta<\/p>\n<p>Se nos fue la adorable Ana Mar\u00eda Matute. Grandiosa escritora. Tan creadora como personaje. Ella se defin\u00eda a s\u00ed misma como &#8220;La Matute&#8221;. Ella, como los grandes talentos que encontrar\u00e9is por el mundo,<strong>\u00a0se so\u00f1\u00f3 a s\u00ed misma<\/strong>. Elabor\u00f3 su estrategia, su objetivo, su personaje, su backstory y su futuro. Pero siempre desde la inocencia. Algo que esta sociedad no perdona y mucho menos la Espa\u00f1a franquista que le toc\u00f3 vivir.<\/p>\n<p>Me identifico totalmente con sus frases. Con su apuesta por la fantas\u00eda; Con su insobornable fe en Dios (&#8220;Me parecer\u00eda una falta de cortes\u00eda que Dios no existiera&#8221;) y, en su caso, en el Gin Tonic. El amigo escritor\u00a0<strong>Manuel Moyano fue a visitarla a su casa cuando fue presidenta del jurado del Premio Setenil y siempre recuerda con una sonrisa las opciones para beber: &#8220;\u00bfQuer\u00e9is t\u00e9 o bourbon?&#8221;<\/strong><\/p>\n<p><strong>Estoy convencida de que la poderosa y creadora energ\u00eda de Ana Mar\u00eda Matute nos dio suerte a todos los que nos implicamos en el ciclo Escritores en su tinta<\/strong>. Fue la segunda invitada y la Biblioteca Salvador Garc\u00eda Aguilar parec\u00eda la iglesia de la boda de Lolita. No cab\u00eda un alma. La gente estaba feliz con los libros de la Matute, atesorados por a\u00f1os en ediciones vetustas; con su gracia, con nuestra falta de comunicaci\u00f3n porque olvid\u00f3 el sonotone, con sus chascarrillos profundos, delirantes, trascendentes de una aplastante sencillez. Esa luz era inigualable.\u00a0<strong>\u00a0Ana Mar\u00eda, hasta el final, ha sido la eterna inmadura, la ni\u00f1a-adolescente de cabellos blancos<\/strong>.<\/p>\n<p><strong>Confieso que las personas inmaduras me han transformado<\/strong>. Hay que tener el valor para abismarse con ellos y &#8220;volar&#8221;. Algo que se auto proh\u00edbe la mayor\u00eda de este pa\u00eds &#8220;conlaqueest\u00e1cayendo&#8221;. El resultado es una sociedad amuermada \u00bfSab\u00e9is qu\u00e9? La vida me ha obligado a ser sensata y lo odio con todas mis fuerzas. Por eso,<strong>\u00a0un d\u00eda, decid\u00ed abandonar el rol de Wendy y rescatar la Campanilla que se esconde en todos nosotros<\/strong>. Probemos a jugar. La vida es un juego, o un teatro como dec\u00eda Oscar Wilde. Pong\u00e1monos el disfraz de cordura y responsabilidad el tiempo que sea estrictamente necesario pero no olvidemos so\u00f1ar. S\u00e9 que me repito, pero\u00a0<strong>esta existencia me ha regalado momentos de indescriptible felicidad gracias a que so\u00f1\u00e9; incluso gracias a que me so\u00f1aron. So\u00f1arnos los unos con los otros es mucho mejor que jodernos los unos a los otros \u00bfno cre\u00e9is?<\/strong><br \/>\n<strong><br \/>\n<\/strong><strong>Para vivir hay que tener cojones e inocencia.\u00a0<\/strong>Parece un binomio inconcebible pero recordemos cu\u00e1ntas lecciones de coraje nos han dado nuestros hijos en m\u00e1s de una ocasi\u00f3n. Cu\u00e1nto valor tuvo\u00a0<strong>Ana Mar\u00eda para divorciarse de un marido abusador con los tiempos que corr\u00edan. Porque ella se so\u00f1\u00f3 digna y no permiti\u00f3 que la plomiza y oscura realidad de la posguerra oscureciesen su luz<\/strong>. El precio a pagar fue muy alto pero por eso hoy todos escribimos y hablamos de ella: &#8220;Inventar\u00e9is citas que jam\u00e1s pronunci\u00e9&#8221;, bromeaba.<\/p>\n<p>Cuando alg\u00fan ser querido me recrimina: &#8220;madura&#8221;, o me escucha en silencio mientras niega con la cabeza en plan &#8220;no, Lola, no&#8221;, me aferro m\u00e1s a la ficci\u00f3n. A nuestra ficci\u00f3n.<strong>\u00a0A ese mundo paralelo que primero se sue\u00f1a y luego te acontece. Porque as\u00ed es. De ilusi\u00f3n tambi\u00e9n se vive. Os lo garantizo<\/strong>. La realidad la fabricamos nosotros cada d\u00eda porque\u00a0<strong>todos somos m\u00e1gicos<\/strong>. Ana Mar\u00eda vive en nosotros, en todos los que tuvimos apenas un reflejo fugaz de su brillo, en todos los que nos hemos quedado perdidos en su bosque de palabras porque, como dijo en vida, \u00a0<strong>&#8220;El triunfo de la sensatez es terrible&#8221;.<\/strong><\/p>\n<p>Si te proh\u00edbes so\u00f1ar, ya est\u00e1s muerto.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; \u00a0Con Ana Mar\u00eda Matute en la Biblioteca Salvador Garc\u00eda Aguilar de Molilna de Segura \u00a0en el primer a\u00f1o de Escritores en su tinta Se nos fue la adorable Ana Mar\u00eda Matute. Grandiosa escritora. Tan creadora como personaje. Ella se defin\u00eda a s\u00ed misma como &#8220;La Matute&#8221;. Ella, como los grandes talentos que encontrar\u00e9is [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,84,121,122],"tags":[],"class_list":["post-618","post","type-post","status-publish","format-standard","hentry","category-ana-maria-matute","category-literatura","category-punto-g","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=618"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/618\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}