{"id":626,"date":"2014-07-14T11:10:36","date_gmt":"2014-07-14T11:10:36","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=626"},"modified":"2014-07-14T11:10:36","modified_gmt":"2014-07-14T11:10:36","slug":"626","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2014\/07\/14\/626\/","title":{"rendered":"Parejas reales"},"content":{"rendered":"<div><a href=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/carolyn2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-631\" title=\"carolyn\" src=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/carolyn2.jpg\" alt=\"\" width=\"300\" height=\"272\" srcset=\"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/carolyn2.jpg 500w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/carolyn2-300x272.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<div><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/ralph2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-632\" title=\"ralph\" src=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/ralph2.jpg\" alt=\"\" width=\"300\" height=\"131\" srcset=\"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/ralph2.jpg 635w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/07\/ralph2-300x131.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<div><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div><\/div>\n<div><\/div>\n<div>Hay parejas tan hermosas que uno hasta agradece (literariamente hablando) que muriesen j\u00f3venes.\u00a0\u00a0 No me malinterpret\u00e9is, no soy una coleccionista de cad\u00e1veres pero, sin duda, hay historias de amor que superan la barrera del tiempo porque sus c\u00f3nyuges se fueron juntos y j\u00f3venes. Es el caso de<strong>la atractiva pareja que hac\u00edan John-John Kennedy y Carolyn Bessette. Esta semana se cumplen 15 a\u00f1os del tr\u00e1gico accidente en avioneta que termin\u00f3 con la vida de ambos<\/strong>. Quedaron sepultados bajo el agua en la Playa Philbin de Martha\u2019s Vineyard. Cuando los encontraron, parad\u00f3jicamente, a\u00fan llevaban el cintur\u00f3n de seguridad puesto.<\/div>\n<div><\/div>\n<div>De haber seguido con vida, probablemente, John-John habr\u00eda completado su estela de rubias, propia de la legendaria y atribulada saga de los Kennedy, y Carolyn\u00a0 ser\u00eda una chica divorciada m\u00e1s. Su matrimonio ya entonces se tambaleaba.<\/div>\n<div><\/div>\n<div>Sin embargo, hay otros romances a los que el paso del tiempo hizo grandes. Para ello no fue necesaria la muerte de nadie. Lo \u00fanico importante en estos casos es\u00a0<strong>el valor de lo extraordinario. Como extraordinaria fue la decisi\u00f3n de Charles Dickens de abandonar diez hijos y esposa en plena \u00e9poca victoriana y en su mayor momento de popularidad<\/strong>. El motivo: una joven actriz, Nelly Ternan, que supo encender la pasi\u00f3n de Dickens hasta casi hacerle perder la cabeza. Pronto podremos ver en las pantallas\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=WDMHb3GetIc\"><strong>\u201cLa mujer invisible\u201d<\/strong><\/a>, pel\u00edcula que se adentra en este laberinto, dirigida y protagonizada por Ralph Fiennes y basada en la novela del mismo t\u00edtulo, escrita por Claire Tomalin.<\/div>\n<div><\/div>\n<div><strong>La literatura dentro de la literatura enaltece este romance y nos muestra la peculiar personalidad de Dickens, un hombre hecho de la nada, que trabaj\u00f3 como sus ni\u00f1os esclavizados de Oliver Twist en una f\u00e1brica de bet\u00fan<\/strong>.\u00a0 De enorme vitalidad, pero tambi\u00e9n capaz de destilar cierta crueldad y dureza, Dickens no fue un autor maldito, todo lo contrario, era una celebritie de la \u00e9poca. Poco le importaron las consecuencias y \u201cel qu\u00e9 dir\u00e1n\u201d de su decisi\u00f3n de abandonarlo todo por amor.<strong>Alguien quiso ver en esta historia la repetici\u00f3n de su relaci\u00f3n plat\u00f3nica con su cu\u00f1ada, que muri\u00f3 por una enfermedad fulminante de la noche a la ma\u00f1ana<\/strong>. Se dice que Dickens perdi\u00f3 la inspiraci\u00f3n temporalmente tras este suceso y que llev\u00f3 hasta su muerte el anillo de Mary. As\u00ed que, aqu\u00ed tenemos de nuevo a\u00a0<strong>la muerte que es la que, en definitiva, convierte en ideales pero tambi\u00e9n irreales los grandes amores.<\/strong><\/div>\n<div><strong><br \/>\n<\/strong><\/div>\n<div>Dec\u00eda Dickens que &#8220;<strong>el coraz\u00f3n humano es un instrumento de muchas cuerdas<\/strong>; el perfecto conocedor de los hombres las sabe hacer vibrar todas, como un buen m\u00fasico\u201d. Con los tiempos que corren yo no s\u00e9 vosotros pero me resulta extraordinario hallar a esos virtuosos de la vida. Los hay, quiz\u00e1 que s\u00ed, pero casi siempre sepultados entre toneladas de miedo, cerraz\u00f3n, angustia y pudor.<\/div>\n<div><\/div>\n<div>Acaso Dickens se qued\u00f3 enganchado a Mary porque\u00a0<strong>el amor ideal es como un para\u00edso perdido al que regresar. Pero no olvidemos que era un creador y ese para\u00edso casi siempre existe s\u00f3lo en la mente del autor y, como en el enamoramiento, otorga a seres humanos\u00a0 de carne y hueso, virtudes que no le corresponden ni de lejos<\/strong>. Los escritores nos empe\u00f1amos en crear la vida, en inventarla. Como dec\u00eda Matute, crear es vivir. La realidad nos la fabricamos. Pero no podemos inventar a alguien que ya es. Y es un error pensar que cambiar\u00e1 o querer transformarlo.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<div>En cualquier caso, podemos agarrarnos a eso de\u00a0<strong>la profec\u00eda autocumplida<\/strong>, y creer y esperar lo mejor de alguien a quien queremos pero apoy\u00e1ndole en su debilidad.\u00a0 Quiz\u00e1 esta generosidad sea m\u00e1s valiosa que el amor. Quiz\u00e1 torne lo ideal en fecunda realidad.<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hay parejas tan hermosas que uno hasta agradece (literariamente hablando) que muriesen j\u00f3venes.\u00a0\u00a0 No me malinterpret\u00e9is, no soy una coleccionista de cad\u00e1veres pero, sin duda, hay historias de amor que superan la barrera del tiempo porque sus c\u00f3nyuges se fueron juntos y j\u00f3venes. Es el caso dela atractiva pareja que hac\u00edan John-John Kennedy y Carolyn [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,24,45,57,84,115,121,122],"tags":[],"class_list":["post-626","post","type-post","status-publish","format-standard","hentry","category-amor","category-belleza","category-dickens","category-estereotipos","category-literatura","category-parejas-de-cine","category-punto-g","category-puntog"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=626"}],"version-history":[{"count":0,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/626\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}