{"id":700,"date":"2014-12-08T22:19:10","date_gmt":"2014-12-08T22:19:10","guid":{"rendered":"http:\/\/blogs.laverdad.es\/vivirenelfilo\/?p=700"},"modified":"2018-12-05T11:17:00","modified_gmt":"2018-12-05T11:17:00","slug":"navidades-calientes","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/2014\/12\/08\/navidades-calientes\/","title":{"rendered":"Navidades calientes"},"content":{"rendered":"<div><\/div>\n<div style=\"text-align: center;\"><a href=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/12\/muerdago.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-701\" title=\"muerdago\" src=\"\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/12\/muerdago.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/12\/muerdago.jpg 580w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/12\/muerdago-150x150.jpg 150w, https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-content\/uploads\/sites\/18\/2014\/12\/muerdago-300x300.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/div>\n<div><\/div>\n<div style=\"text-align: center;\"><strong>\u00a0Nueva forma de llevar el mu\u00e9rdago para no perderse ni un beso<\/strong><\/div>\n<div><\/div>\n<div><\/div>\n<div>Se aproximan las fiestas y con ellas algunas encuestas absurdas sobre los h\u00e1bitos sexuales de los espa\u00f1oles. No s\u00e9 c\u00f3mo se lo montar\u00e1 la\u00a0<strong>agencia de\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">contactos<\/a>\u00a0Ashley Madison<\/strong>para que la gente conteste a semejantes tonter\u00edas. Veamos. Cuando uno va a casa de los suegros en lo \u00faltimo que piensa es en echar un quiqui. Vamos, que si la cosa aprieta y no hay m\u00e1s remedio, se puede hacer con el morbo a\u00f1adido de que nadie te pille.\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">Pero<\/a>\u00a0seg\u00fan esta agencia,\u00a0<strong>el 60% de los espa\u00f1oles ha tenido o espera tener\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">relaciones sexuales<\/a>\u00a0en las casas de las familias pol\u00edticas esta navidad. No s\u00f3lo eso, sino que al 84% de los hombres lo que les pone es utilizar el cuarto de la infancia de ella<\/strong>, desterrar los peluches y llenar el edred\u00f3n infantil de juegos y perversi\u00f3n. Que quer\u00e9is que os diga, me da cierta grima. Imag\u00ednate: la Nancy, el Baby mocosete; el platito de &#8220;Te quiero, mam\u00e1&#8221; y t\u00fa sudando la sidra entre gemidos y gritos con silenciador. Esto no me pone nada. De hecho, nosotras somos m\u00e1s de cuarto de invitados.<\/div>\n<div><\/div>\n<div>La empresa de contactos tambi\u00e9n pregunta\u00a0<strong>si ellos ven porno durante las fiestas con los cu\u00f1ados pegados al lomo. La respuesta es s\u00ed:\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">hasta<\/a>\u00a0un 79%.\u00a0 Es m\u00e1s, la encuesta revela que ellos disimulan y se ponen al vicio en cuanto los padres de ella se despistan y que el 71% utiliza una tablet para tal fin<\/strong>.<\/div>\n<div><\/div>\n<div>Con estas cifras, bien parece que los espa\u00f1oles son todos una<strong>panda de s\u00e1tiros incapaces de estar tres d\u00edas en\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">casa<\/a>\u00a0de los parientes sin dejar de pensar en lo \u00fanico por un momento y concentrarse en el pavo, las tortas de pascua,<\/strong>\u00a0el discurso del rey Felipe VI o las viejas discusiones y rencillas familiares, que nunca faltan en ninguna reuni\u00f3n que se precie. Vistas as\u00ed las cosas, los encuestados de Mashley Adison hasta me caen bien, incluso los hay que piensan en\u00a0<strong>mont\u00e1rselo con la cu\u00f1ada. Jes\u00fas. No lo entiendo. Quiz\u00e1 tenga una moral de mari casta\u00f1a pero es que jam\u00e1s de los jamases le he encontrado el m\u00e1s m\u00ednimo sex appeal a la figura del cu\u00f1aaooo<\/strong>.<\/div>\n<div><\/div>\n<div>Es cierto que s\u00ed pone\u00a0<strong>hacer el amor en sitios diferentes, cambiar de entorno<\/strong>. Mis seguidores de Facebook, con su generosidad habitual me han contado los sitios raros donde se lo han montado con alguien que les gustaba, incluso con su pareja de toda la vida. Los hay que han pasado por el backstage, otros por el ineludible\u00a0<strong>cuarto de ba\u00f1o de un garito, la providencial arena de la playa y el mar<\/strong>, y el cl\u00e1sico huerto.<\/div>\n<div>Los conciertos dan mucho juego. Algunos lo han hecho<strong>\u00a0en medio de una canci\u00f3n de Simple Minds o de Alejandro Sanz, e incluso escondidos tras la tramoya de un recital c<\/strong>l\u00e1sico de piano. Ay, bendito!.Imagino los silencios. Los del pianista y los de ellos porque, anda que no hay que contenerse en casos as\u00ed.<\/div>\n<div><\/div>\n<div>No falta la proverbial\u00a0<strong>mesa de oficina en plan &#8220;El cartero siempre llama dos veces&#8221;<\/strong>. Los hay osados que\u00a0 se apuntan meterse mano entre las ruina; los hay experimentales que mezclan los fluidos con los vinilos y tipos de una vieja imprenta y los que regresan al buc\u00f3lico pajar para mont\u00e1rselo entre panochas.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<div>Total, que los encuestados de Ashley Madison me resultan sosos al lado de mis intr\u00e9pidos seguidores de FB \u00a0\u00a1\u00a1Y que algo tan elemental\u00a0<a href=\"http:\/\/lola-gracia.blogspot.com.es\/2014\/12\/navidades-calientes.html#\">como<\/a>\u00a0hacerlo bajo las lucecitas del \u00e1rbol de navidad no se le ha ocurrido a nadie!!. A mi s\u00ed. Es un viejo sue\u00f1o, quiz\u00e1 me lo conceda el viejo Santa Claus.<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00a0Nueva forma de llevar el mu\u00e9rdago para no perderse ni un beso Se aproximan las fiestas y con ellas algunas encuestas absurdas sobre los h\u00e1bitos sexuales de los espa\u00f1oles. No s\u00e9 c\u00f3mo se lo montar\u00e1 la\u00a0agencia de\u00a0contactos\u00a0Ashley Madisonpara que la gente conteste a semejantes tonter\u00edas. Veamos. Cuando uno va a casa de los suegros en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122,131],"tags":[],"class_list":["post-700","post","type-post","status-publish","format-standard","hentry","category-puntog","category-sexo"],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":1,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":1411,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/posts\/700\/revisions\/1411"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/vivirenelfilo\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}