{"id":1371,"date":"2020-02-14T11:14:47","date_gmt":"2020-02-14T10:14:47","guid":{"rendered":"https:\/\/blogs.laverdad.es\/zonadeembarque\/?p=1371"},"modified":"2020-02-14T11:14:47","modified_gmt":"2020-02-14T10:14:47","slug":"santander-en-un-plano-muy-amoroso","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/zonadeembarque\/2020\/02\/14\/santander-en-un-plano-muy-amoroso\/","title":{"rendered":"Santander en un plano muy amoroso"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Calibri;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Estos d\u00edas de mitad de febrero ya se empieza a notar la primavera. Cupido se cuela en casi todas las tiendas y restaurantes con decoraciones y cenas que prometen mucha pasi\u00f3n despu\u00e9s del postre. Por el Sur, los primeros almendros se abren para competir en belleza. Les propongo unir el d\u00eda de los enamorados con la cultura.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Nuestro destino nos lleva al Norte. Daremos un paseo por Santander lleno de ternura. Comenzamos la ruta en la misma orilla del mar. <a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/miguelarribared.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1372 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/miguelarribared-223x300.jpg\" alt=\"\" width=\"223\" height=\"300\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/miguelarribared-223x300.jpg 223w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/miguelarribared.jpg 570w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/a><\/span><\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">Lenguaje casi secreto<\/span><\/strong><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Cruzamos las puertas del Museo Mar\u00edtimo del Cant\u00e1brico. Y una de sus obras (en la planta segunda) s\u00f3lo se puede leer en clave cifrada. En una corta distancia con un poquito de curiosidad y, salta la magia.\u00a0En una de sus paredes se puede ver la \u201cCarta de un enamorado eterno\u201d de Eduardo Sanz. Est\u00e1 \u201cescrita\u201d con banderas mar\u00edtimas y relata una historia de amor que comienza con el despertar de las aventuras y destellos de la infancia. Ese momento cuando te sonr\u00ede por primera vez alguien que te gusta. La fotograf\u00eda es de Miguel Arriba (cedida por cortes\u00eda del Museo). Si la miran bien, podr\u00e1n observar la silueta de un faro tambi\u00e9n un poco jugando al escondite. Yo cuando la vi por primera vez me qued\u00e9 embelesada \u201cleyendo\u201d esta carta. Y es que el amor atrapa de una manera que\u2026<\/span><\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">Hip\u00e9rbole amorosa: una pared con alma marinera<\/span><\/strong><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Dicen los expertos ling\u00fcistas que la palabra amor siempre ha de serlo a lo grande, de forma exagerada porque va de suyo esta vis expansiva que tiene nada m\u00e1s sentirlo. Por esta raz\u00f3n, despu\u00e9s de admirar el lienzo, continuamos nuestro paseo amoroso por la toda ciudad. Les llevo a otro rinc\u00f3n que, para m\u00ed, rebosa ternura: el Mural Sotileza, otra gran obra de arte.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Es una medianera que\u00a0me recuerda a las aventuras de aquellos de 13 Rue del Percebe. Todas sus ventanas y balcones relatan una historia de sus habitantes y, todas unidas por el amor al mar: el pescado recogido ese d\u00eda; las redes puestas a secar; el desaf\u00edo ante las tormentas\u2026 <a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santander2r3d.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1373 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santander2r3d-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santander2r3d-300x225.jpg 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santander2r3d.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Esta parada tiene su peligro. Porque se encuentra junto a las estaciones de autob\u00fas y de tren. Y claro de tan bonita que es, a poco que uno sea un poco cotilla y quiera \u201cconocer\u201d a todos los vecinos, si va con poco tiempo es posible que pueda perder el autob\u00fas. Porque ya les aviso: la pared \u2013como el cuadro de las banderas mar\u00edtimas- embelesa.<\/span><\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">Las 3D santanderinas<\/span><\/strong><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Santander se puede visitar en tres planos distintos, como si fuera un puzzle de Lego. El primer nivel transcurre a lo largo de la franja mar\u00edtima, casi a ras de la playa. Por una balconada que une casi todas las playas.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">La segunda dimensi\u00f3n ya lo es a pie de calle. El paseo de Pereda, la Avenida de la Reina Victoria, Avenida Casta\u00f1eda y, si uno es de los que deja que los pies contin\u00faen, tras unos kil\u00f3metros de sentir la brisa del mar, llega hasta el Faro de Cabo Mayor que, como en la carta, est\u00e1 escondido despu\u00e9s de atravesar una pinada. Cuando voy con amigos a Santander, el primer paseo para que conozcan la ciudad es esta ruta a lo largo de la costa. Si puedo, calculo bien para que el atardecer nos pille justo cuando alcanzamos la base del Faro. De ah\u00ed a quedar enamorados de la ciudad, es casi un flechazo. Amor a primera\u2026 &#8220;visita&#8221;, me comentan luego. <a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santanderballenared.png\"><img loading=\"lazy\" class=\"size-medium wp-image-1374 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santanderballenared-300x225.png\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santanderballenared-300x225.png 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santanderballenared.png 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Y la tercera dimensi\u00f3n vertical de esta ciudad tan amorosa transcurre entre cuestas y paseos. El Mirador de R\u00edo de Pila es uno de los puntos elegidos para esta visi\u00f3n panor\u00e1mica. No se preocupen que hay escaleras autom\u00e1ticas y funicular para \u201cla escalada\u201d.<\/span><\/p>\n<p><strong><span style=\"color: #000000; font-family: Calibri;\">El arrebato amoroso<\/span><\/strong><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Recuerden que en Santander las cosas no son lo que parecen. En esta ciudad, una magdalena, lejos de ser comestible, es un bell\u00edsimo palacio ubicado en lo alto de una pen\u00ednsula; Un \u201ccamello\u201d sabe nadar y, hasta es posible ver una gigantesca \u201cballena\u201d varada junto al Parque Atl\u00e1ntico de Las Llamas. <a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santandercamellored.png\"><img loading=\"lazy\" class=\"size-medium wp-image-1375 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santandercamellored-300x225.png\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santandercamellored-300x225.png 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/02\/santandercamellored.png 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">Porque s\u00ed, el amor nos confunde a todos. Y cuando est\u00e1 por toda la ciudad de qu\u00e9 forma tan bella lo hace.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Calibri;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 &nbsp; Estos d\u00edas de mitad de febrero ya se empieza a notar la primavera. Cupido se cuela en casi todas las tiendas y restaurantes con decoraciones y cenas que prometen mucha pasi\u00f3n despu\u00e9s del postre. Por el Sur, los primeros almendros se abren para competir en belleza. Les propongo unir el d\u00eda de [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,15,18,40,56],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1371"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/comments?post=1371"}],"version-history":[{"count":2,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1371\/revisions"}],"predecessor-version":[{"id":1377,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1371\/revisions\/1377"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/media?parent=1371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/categories?post=1371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/tags?post=1371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}