{"id":1453,"date":"2020-10-21T20:01:40","date_gmt":"2020-10-21T18:01:40","guid":{"rendered":"https:\/\/blogs.laverdad.es\/zonadeembarque\/?p=1453"},"modified":"2020-10-23T09:16:14","modified_gmt":"2020-10-23T07:16:14","slug":"tempus-fugit-seguro","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/zonadeembarque\/2020\/10\/21\/tempus-fugit-seguro\/","title":{"rendered":"Tempus fugit, \u00bfseguro?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Que si el tiempo pasa volando. Que si despu\u00e9s de los cuarenta, la velocidad ya es supers\u00f3nica. Que si una hora de espera, es una eternidad (y dicen los expertos que ya no existe nadie con tanta paciencia). El vivir parece ser cosa de apremio y urgencia.<\/p>\n<p>Ante ello, cu\u00e1nto significado adquieren esos lugares que parece supieron hacer su pacto con el diablo y podemos visitarlos en un \u201csu eterna juventud\u201d. Les invito a tomar un aperitivo con los mism\u00edsimos romanos. Pago yo la cuenta.<\/p>\n<p>La gran sabidur\u00eda de los tiempos de Roma se extend\u00eda a las artes de la pesca. Adem\u00e1s de ingenieros y constructores de primera, supieron construir unas \u201cpiscifactor\u00edas\u201d en la misma costa, a pie de playa. Estaban dise\u00f1adas a modo de laberintos; En ellas, los peces, una vez dentro ya no pod\u00edan escapar.\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/PISCICALPERED.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1454 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/PISCICALPERED-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/PISCICALPERED-300x150.jpg 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/PISCICALPERED-768x385.jpg 768w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/PISCICALPERED.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Entre piscifactor\u00edas y piscinas: un piscolabis<\/strong><\/p>\n<p>Se pueden a\u00fan ver en varias ciudades de la costa levantina. Especialmente bonitos son los denominados \u201cBa\u00f1os de la Reina\u201d de Calpe y de El Campello. Funcionaban como si fueran unas \u201calmadrabas de rocas\u201d. En la \u00faltima de las balsas-piscinas los dejaban secar. Y de ah\u00ed, a la mesa con la famosa salsa garo y los salazones.<\/p>\n<p>Este lugar calpino es uno de los favoritos para practicar snorkel: anta\u00f1o una piscifactor\u00eda, hoy, toda una maravilla de acuario en libertad (pulpos, erizos, por\u00edferos\u2026) y, coincidencias bonitas que tiene la vida: all\u00ed est\u00e1bamos con nuestro aperitivo de mojama y hueva. S\u00ed, la versi\u00f3n actualizada de los mismos manjares que se produc\u00edan en el mismo lugar hace unos 2.000 a\u00f1os. Ya les digo: sentados bajo el sol cual \u201cromanos contempor\u00e1neos\u201d.<\/p>\n<p>En el Museo de la Historia de Calpe se explica con gran detalle c\u00f3mo se constru\u00edan estas balsas talladas en la roca, con el doble itinerario de estar entre s\u00ed unidas y, a su vez, tambi\u00e9n con mar abierto. Su destino era la producci\u00f3n local (al modo de pescader\u00edas en el siglo I. a C.) pero tambi\u00e9n eran parte de las lujosas villas romanas.\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/calperedba\u00f1os.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1455 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/calperedba\u00f1os-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/calperedba\u00f1os-300x200.jpg 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/calperedba\u00f1os-768x512.jpg 768w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/calperedba\u00f1os.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Chapoteos<\/strong><\/p>\n<p>A pocos kil\u00f3metros de distancia, siguiendo en esta misma zona de costa levantina, se puede visitar \u201cla Villa Romana de L\u2019Albir\u201d (en L\u2019Alfas del Pi). Fue la casa (hoy dir\u00edamos mansi\u00f3n) de una familia romana muy adinerada. En su propiedad ten\u00edan la almazara en el propio jard\u00edn y tambi\u00e9n las termas.<\/p>\n<p>Y, nuevamente, coincidencias y reiteraciones tiene la vida, los vecinos actuales de aquella lujosa residencia romana, tienen construida su piscina, pared con pared, con las antiguas termas. El dato curioso es que se pueden visitar las termas con el sonido del agua de fondo de los chapoteos y brazadas de los colindantes.<\/p>\n<p><strong>\u00bfLa bolsa o la vida?<\/strong><\/p>\n<p>En este <em>continuum<\/em> del vivir, vemos c\u00f3mo se repiten las pandemias. Aquel viejo dilema que le\u00edamos en los cuentos infantiles cuando el personaje malo aparec\u00eda por sorpresa, est\u00e1 vigente: salvar la salud o la econom\u00eda.<\/p>\n<p>Aquel viejo tiempo que volaba, parece quedar en ocasiones detenido e inamovible. \u00bfQu\u00e9 entregamos al asaltante: la vida o la bolsa? Es, desgraciadamente, la pregunta actual ante la que no tenemos respuesta.<\/p>\n<p><strong>Una fotograf\u00eda\u2026 \u00bfsine die?\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/egipciored.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1456 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/egipciored-238x300.jpg\" alt=\"\" width=\"238\" height=\"300\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/egipciored-238x300.jpg 238w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/10\/egipciored.jpg 508w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/><\/a><\/strong><\/p>\n<p>La escritora Natalia Ginzburg sosten\u00eda que <em>\u201cnuestra existencia se desarrolla seg\u00fan leyes antiguas e inmutables; existe una cierta uniformidad mon\u00f3tona en los destinos de los hombres\u201d<\/em><\/p>\n<p>Creemos que somos originales, innovadores, pero\u2026 \u00bfrealmente hemos avanzado? Hace 3000 a\u00f1os un egipcio podr\u00eda estar delante de su casa viendo este campo de alfalfa con las palmeras detr\u00e1s. Hoy, en el siglo XXI, en otra parte del Mediterr\u00e1neo, pensemos en un murciano, podr\u00eda tener id\u00e9nticas vistas justo ante su vivienda. Podr\u00e1n ver a lo lejos la hilera del tendido el\u00e9ctrico, porque s\u00ed, hay constantes vitales pero tambi\u00e9n junto a ellas, paso a paso\u2026 se hace el camino como nos ense\u00f1aba Machado.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Que si el tiempo pasa volando. Que si despu\u00e9s de los cuarenta, la velocidad ya es supers\u00f3nica. Que si una hora de espera, es una eternidad (y dicen los expertos que ya no existe nadie con tanta paciencia). El vivir parece ser cosa de apremio y urgencia. Ante ello, cu\u00e1nto significado adquieren esos lugares [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,18,20,25,40,46,61,65,66],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1453"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":6,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":1462,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1453\/revisions\/1462"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}