{"id":1464,"date":"2020-11-06T09:08:19","date_gmt":"2020-11-06T08:08:19","guid":{"rendered":"https:\/\/blogs.laverdad.es\/zonadeembarque\/?p=1464"},"modified":"2020-11-06T10:14:51","modified_gmt":"2020-11-06T09:14:51","slug":"flores-en-la-paella","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/zonadeembarque\/2020\/11\/06\/flores-en-la-paella\/","title":{"rendered":"Flores en la paella"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Esa tendencia a ver el mundo en dos dimensiones opuestas (tortilla de patatas con o sin cebolla; Real Madrid o Bar\u00e7a; derechas\/izquierdas; pijama\/camis\u00f3n, o ya en versi\u00f3n m\u00e1s oto\u00f1al: edred\u00f3n\/manta; vayan a los bares a mover la econom\u00eda\/ci\u00e9rrense por decreto) no se da en nuestro plato m\u00e1s universal: la paella. Aqu\u00ed, afortunadamente, no hay enfrentamientos.<\/p>\n<p>Para documentarme bien ha llevado a cabo un previo estudio de mercado con una pregunta directa al coraz\u00f3n, digo, al cuchar\u00f3n: \u00bfEres de piment\u00f3n o de azafr\u00e1n? Y muchos han sido los que no ten\u00edan su \u201ccoraz\u00f3n part\u00edo\u201d, sino que a\u00f1ad\u00edan directamente los dos: \u201cporque uno colorea y otro, adem\u00e1s, sabrosea\u201d me contestaba Mar\u00eda Luisa, en un nivel propio de un finalista en Master Chef.\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/azaharred.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1466 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/azaharred-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/azaharred-300x225.jpg 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/azaharred.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A m\u00ed me encanta compartir con turistas y amigos extranjeros la que es su \u201cprimera vez\u201d con el descubrimiento de la paella. Yo ya les advierto: \u201cVas a comer flores\u201d. Me miran siempre con cara de incr\u00e9dulos. Ellos solo ven el arroz.<\/p>\n<p><strong>Dos territorios paelleros<\/strong><\/p>\n<p>Valencia y La Mancha caminan juntos en esta delicia espa\u00f1ola. El recorrido en barco por La Albufera es clave para conocer el ingrediente m\u00e1s famoso: el arroz. Tras esta primera magia, hay que detenerse despu\u00e9s tierra adentro, all\u00ed donde se cultiva la flor del azafr\u00e1n. Que es la que le dar\u00e1 sabor y color. \u201cSegundo toque m\u00e1gico\u201d, les aviso nuevamente a mis comensales principiantes.<\/p>\n<p><strong>Nombre muy familiar<\/strong><\/p>\n<p>Consuegra (Toledo) todos los a\u00f1os despide el mes de octubre con la celebraci\u00f3n de la <strong>Fiesta de la Rosa del Azafr\u00e1n.<\/strong> En estos d\u00edas se puede ver en directo y compartir todo el proceso de la monda de las flores con los agricultores y las cosechadoras quitando los tres pistilos con suma delicadeza. Es de esas labores artesanas que ten\u00edan la fortaleza de unir a toda la familia (peque\u00f1os y mayores). Hace a\u00f1os esta flor era utilizada en el sabio sistema de descanso de tierras en pos de su fertilidad y evitar tambi\u00e9n el \u00e9xodo de mano de obra.<\/p>\n<p>Espa\u00f1a compite con Ir\u00e1n en el lugar de los mejores del mundo en el cultivo de este \u201coro rojo\u201d. Este valioso producto tiene reconocida su propia Denominaci\u00f3n de Origen. Les cuento dos de sus requisitos legales. El tama\u00f1o m\u00e1ximo permitido en tarros de venta al p\u00fablico no puede superar los 100 gramos (con ello se evitan posibles reventas que puedan distorsionar los precios) y, debe ser vendido necesariamente en hebras, nunca molido (con el fin de no dar lugar a alteraciones en su composici\u00f3n).<\/p>\n<p><strong>De la monda a la molienda<\/strong><\/p>\n<p>Otra de las actividades bien bonitas de este Festival es la \u201cMolienda de la Paz y del Amor\u201d. Este a\u00f1o ha estado dedicada a las v\u00edctimas del Covid.\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/consuegramolinosred.png\"><img loading=\"lazy\" class=\"size-medium wp-image-1467 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/consuegramolinosred-300x225.png\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/consuegramolinosred-300x225.png 300w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2020\/11\/consuegramolinosred.png 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es impresionante ver el funcionamiento de los molinos de viento y c\u00f3mo en pleno siglo XXI estos \u201cgigantes\u201d derrochan sabidur\u00eda en todas sus piezas y maquinaria para fabricar harina. Juan, el molinero, domina con maestr\u00eda los trucos para controlar el viento. Es \u201ccomo un velero en tierra firme\u201d nos contaba. Eres todo \u201cun capit\u00e1n\u201d, respond\u00edamos convencidos todos.<\/p>\n<p><strong>Provoca una sonrisa<\/strong><\/p>\n<p>Allende los mares un grupo de se\u00f1oras lo ten\u00edan claro: <strong>\u201cla paella es una sonrisa\u201d<\/strong>, afirmaban casi al un\u00edsono. Hagan la prueba. Est\u00e9n bien atentos en ese momento de llevarla al centro de la mesa. Si entre sus comensales se encuentra alg\u00fan invitado extranjero que la ve por primera vez, no falla: es verla aparecer y sonre\u00edr. Bueno, he de decirles, que a muchos todav\u00eda ese gran c\u00edrculo amarillo nos sigue provocando este efecto inexplicado de felicidad gastron\u00f3mica.<\/p>\n<p>Porque, no quisiera yo echar m\u00e1s le\u00f1a al fuego (no vaya a ser que se nos queme el arroz) pero\u2026 \u00bfno les llama la atenci\u00f3n el gran parecido del dise\u00f1o del famoso \u201csmiley\u201d, esa carita sonriente amarilla con la paella? Mira que si, el dise\u00f1ador en una de estas sonrisas al probarla\u2026<\/p>\n<p>\u00a1Ay, que me dejo llevar por la imaginaci\u00f3n&#8230;! (Suj\u00e9tame Sancho que el mundo de la locura y la sensatez tambi\u00e9n caminan juntos).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esa tendencia a ver el mundo en dos dimensiones opuestas (tortilla de patatas con o sin cebolla; Real Madrid o Bar\u00e7a; derechas\/izquierdas; pijama\/camis\u00f3n, o ya en versi\u00f3n m\u00e1s oto\u00f1al: edred\u00f3n\/manta; vayan a los bares a mover la econom\u00eda\/ci\u00e9rrense por decreto) no se da en nuestro plato m\u00e1s universal: la paella. Aqu\u00ed, afortunadamente, no hay [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15,18,25,65,67],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1464"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":7,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1473,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1473"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}