{"id":1628,"date":"2022-10-26T13:28:24","date_gmt":"2022-10-26T11:28:24","guid":{"rendered":"https:\/\/blogs.laverdad.es\/zonadeembarque\/?p=1628"},"modified":"2022-11-28T09:31:21","modified_gmt":"2022-11-28T08:31:21","slug":"ciencias-y-letras-se-pasean-por-la-calle","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/zonadeembarque\/2022\/10\/26\/ciencias-y-letras-se-pasean-por-la-calle\/","title":{"rendered":"Los nombres de las calles"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quisiera resolver el gran enigma de los nombres de las calles. Desde un cruas\u00e1n en la 5\u00aa Avenida de Nueva York a una horchata en una calle de Valencia. \u00bfSe animan Vds. a recorrer este sabroso callejero?<\/p>\n<p>Si comenzamos a lo grande, en Nueva York el dilema de c\u00f3mo identificar las calles se solucion\u00f3 en un plan cuadriculado, con numeraci\u00f3n matem\u00e1tica: las avenidas tienen sentido vertical (en la quinta es imposible no detenerse; incluso desayunar elegantemente frente al escaparate de Tiffany\u2019s). Y, en sentido horizontal las calles se numeran desde el Sur. Pero, -para que los de letras no se pierdan con tantos ordinales-, la excepci\u00f3n es la Avda. Broadway que rompe esta \u201csencilla\u201d cuadr\u00edcula y atraviesa Manhattan en diagonal.<\/p>\n<p>Cuando callejeaba con una amiga, encontr\u00f3 una posible raz\u00f3n. Yo not\u00e9 un poco de a\u00f1oranza de Espa\u00f1a: \u201cNo se quisieron complicar la cabeza: N\u00fameros y ancha es Manhattan\u201d.<\/p>\n<p><strong>Desde el Atl\u00e1ntico al Mediterr\u00e1neo<\/strong><\/p>\n<p>Pero si acudimos a otra poblaci\u00f3n, ya de menor tama\u00f1o, merece la pena detenernos junto al Mediterr\u00e1neo. En la costa levantina Dehesa de Campoamor (Alicante) rebosa cultura en todo su asfalto: las calles toman el nombre de escritores y, los edificios, de r\u00edos; Es imposible ir a visitar a un amigo y no haber aprendido alg\u00fan escritor o r\u00edo desconocido hasta entonces. Es toda una clase de geograf\u00eda y literatura donde las haya. El poeta Ram\u00f3n de Campoamor, que estuvo por all\u00ed un tiempo, tal vez inspir\u00f3 este sello <em>sui generis<\/em> en la urbanizaci\u00f3n.<\/p>\n<p><strong>Razones de ley. Y tambi\u00e9n, de peso.<\/strong><\/p>\n<p>Tras este recorrido, llegamos a las Ordenanzas municipales que son las dilucidan estos menesteres de dar nombres al callejero. Y nuestro destino final -sin salirnos de la costa mediterr\u00e1nea- nos conduce a una avenida en Valencia que el nombre lo tiene a resultas del buen hacer de una helader\u00eda. Ah\u00ed es nada: uno regenta un negocio, lo hace tan bien, que la calle entera toma el nombre de los productos que vende.<\/p>\n<p><strong>Avenida de la Horchata<\/strong><\/p>\n<p>S\u00ed, es este helado tan t\u00edpicamente valenciano el que da el nombre a la famosa Avinguda de l\u2019Orxata en la Alboraya (Valencia).<\/p>\n<p>Se trata de un negocio familiar de varias generaciones (va por la tercera). Despu\u00e9s de muchos a\u00f1os de trabajo deciden por su cuenta y riesgo abrir un obrador especializado en horchata fuera de la ciudad, en plena huerta de la Alboraya. Al helado le unen los \u201cfartons\u201d, que ten\u00edan la resistencia perfecta ya que pod\u00edan embeber la bebida sin llegar a romperse (muy significativa es su traducci\u00f3n de &lt;&lt;glot\u00f3n&gt;&gt;). Y claro, aquello de: \u201c\u00bfD\u00f3nde vas?\u201d, por sabrosura se lleg\u00f3 a: \u201cVoy a la Avinguda de l\u2019Orxata\u201d. Y hasta hoy.<\/p>\n<p>La historia ha quedado incorporada en la carta men\u00fa de la Helader\u00eda Daniel. Salvador Dal\u00ed y Rafael Albert\u00ed estuvieron en el local. Incluso cuentan los de lugar que un sult\u00e1n, alertado por tan goloso nombre de la avenida, pis\u00f3 a tope el freno de su Rolls y se detuvo para tomar el refresco.\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2022\/10\/horchatared.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1629 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2022\/10\/horchatared-298x300.jpg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2022\/10\/horchatared-298x300.jpg 298w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2022\/10\/horchatared-150x150.jpg 150w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2022\/10\/horchatared.jpg 635w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/><\/a><\/p>\n<p>Esta calle se encuentra en uno de los accesos a la Alboraya. Seguramente, ser\u00e1n muchos los que, si est\u00e1n a r\u00e9gimen, hasta sean capaces de dar un rodeo para evitar tantas tentaciones.<\/p>\n<p>Lo que m\u00e1s me gusta (claro que, a estas alturas, aunque intuyo que ya lo habr\u00e1n notado, debo confesarles que soy forofa de la horchata en todas sus variantes: de chufa, almendra, avellana. S\u00ed, vaya que yo tambi\u00e9n pis\u00e9 el freno) es que el buen hacer de una empresa sea reconocido, como lo puede ser igualmente una labor a t\u00edtulo personal.<\/p>\n<p><strong>Nada es verdad ni mentira<\/strong><\/p>\n<p>Pero hay misterios que quedan sin soluci\u00f3n por mucho que se indague. En Murcia, la \u201cAvda. de los Pinos\u201d est\u00e1 repleta de\u2026 \u00a1palmeras! Intrigas que tiene la vida, digo, el callejero. O, \u00bfser\u00e1 que \u201ctodo es seg\u00fan el color del cristal\u201d como dec\u00eda Campoamor?<\/p>\n<p>En calles con nombres as\u00ed, que juegan al enga\u00f1o, hasta los de ciencias se pueden perder en ellas. Voy a mirar bien la pr\u00f3xima vez que pase, no vaya a ser que, en alg\u00fan recoveco o parterre est\u00e9 brotando un peque\u00f1o pino y&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Quisiera resolver el gran enigma de los nombres de las calles. Desde un cruas\u00e1n en la 5\u00aa Avenida de Nueva York a una horchata en una calle de Valencia. \u00bfSe animan Vds. a recorrer este sabroso callejero? Si comenzamos a lo grande, en Nueva York el dilema de c\u00f3mo identificar las calles se [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15,18,25,39,42,58,65],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1628"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/comments?post=1628"}],"version-history":[{"count":4,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1628\/revisions"}],"predecessor-version":[{"id":1636,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1628\/revisions\/1636"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/media?parent=1628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/categories?post=1628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/tags?post=1628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}