{"id":1644,"date":"2023-01-23T12:45:10","date_gmt":"2023-01-23T11:45:10","guid":{"rendered":"https:\/\/blogs.laverdad.es\/zonadeembarque\/?p=1644"},"modified":"2023-01-23T13:34:51","modified_gmt":"2023-01-23T12:34:51","slug":"donde-el-corazon-te-lleve","status":"publish","type":"post","link":"https:\/\/blogs.laverdad.es\/zonadeembarque\/2023\/01\/23\/donde-el-corazon-te-lleve\/","title":{"rendered":"Donde el coraz\u00f3n te lleve"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>El primer mes del a\u00f1o viene con esta doble faz del dios Jano que a\u00fan mira al pasado, pero a la vez, puede girar hacia el futuro. Es lo todos conocemos como saber aprender del pasado para tomar sabias decisiones.<\/p>\n<p>Y al pasado que nos vamos, concretamente a aquellos remotos tiempos en los que s\u00f3lo exist\u00eda la inteligencia natural; A la \u00e9poca de las pinturas rupestres, concretamente haremos una ruta a pie por el monte Arab\u00ed de Yecla (Murcia). Para m\u00ed son toda una \u201cAltamira murciana\u201d. (S\u00ed, orgullo que en estos rincones asoma).<\/p>\n<p>Al igual que las de la cornisa c\u00e1ntabra (\u00bfVen? Son muchos parecidos como les dec\u00eda) han sido declaradas Patrimonio de la Humanidad bajo el itinerario de \u201cArte Rupestre del Arco Mediterr\u00e1neo de la Pen\u00ednsula Ib\u00e9rica\u201d. Yo creo que en la sospecha fundada de que puedan aparecer muchas m\u00e1s. Optimismo que no falte, que estamos estrenando el a\u00f1o.<\/p>\n<p>Los dibujos, en uno de los <strong>Cantos de Visera<\/strong>, representan con mucha exactitud los animales (toros, caballos&#8230;). En otra cavidad ya la representaci\u00f3n lo es de forma simb\u00f3lica. Avanzados nuestros trogloditas del Sur.<\/p>\n<p><strong>En compa\u00f1\u00eda del arque\u00f3logo, Indiana Jones\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/montearabired.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1645 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/montearabired-239x300.jpg\" alt=\"\" width=\"239\" height=\"300\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/montearabired-239x300.jpg 239w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/montearabired.jpg 510w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/a><\/strong><\/p>\n<p>Siguiendo esta una ruta de senderismo nos conduce al rinc\u00f3n de las denominadas <strong>\u201cCazoletas\u201d<\/strong>. Son unas incrustaciones en la roca (<em>insculturas<\/em> me indicaba el gu\u00eda). El homo sapiens (con su inteligencia artificial) a\u00fan no ha podido descifrar con exactitud si estos petroglifos eran una invocaci\u00f3n a la lluvia; tal vez una representaci\u00f3n del cielo; quiz\u00e1s algo l\u00fadico\u2026 Gran misterio el de estas incisiones que asemejan mucho a nuestro juego de damas actual.<\/p>\n<p>El punto de m\u00e1xima alegr\u00eda, \u201cel santo Grial\u201d de esta ruta es la llegada al <em>Oculus Dei<\/em>: <strong>\u201cLa Cueva Horadada\u201d<\/strong>.\u00a0 Una grand\u00edsima cueva, por la que se puede transitar, se abre al cielo de una forma casi m\u00e1gica. Precisamente fue este dato, la magia de este entorno que data del IV al II Milenio a.C. la que motiv\u00f3 que todo el equipo televiso de Cuarto Milenio se desplazara para comprobar\u00a0<em>in situ <\/em>los misterios, las leyendas y los avistamientos de extraterrestres. Mira que si este gran orificio circular en la monta\u00f1a\u2026<\/p>\n<p>El interior de esta gran cavidad es de una belleza asombrosa porque el material rocoso se ha formado con las huellas del agua y del viento quedando como si fuera una esponja natural en la monta\u00f1a.<\/p>\n<p>\u00bfPodr\u00eda haber ejercido libremente el Sr. Jones su profesi\u00f3n de cazatesoros por estas lindes? Una de las leyendas m\u00e1s arraigadas es el hallazgo de un tesoro. Tres extranjeros dejaron sus caballos al cuidado de unos agricultores de la zona. Al regresar a por los animales, abonaron este dep\u00f3sito con una gran moneda de oro. Sospechosamente iban cargados con unos grandes sacos. Hoy, si encontr\u00e1ramos otros (sigamos siendo optimistas), tendr\u00edamos que aplicar el art\u00edculo 351 del C\u00f3digo civil:\u00a0\u201cel tesoro oculto pertenece al due\u00f1o del terreno en que se hallare\u201d. Claro que este art\u00edculo tiene muchas excepciones y&#8230;\u00a0<a href=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/Yecla3red.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1646 alignright\" src=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/Yecla3red-234x300.jpg\" alt=\"\" width=\"234\" height=\"300\" srcset=\"https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/Yecla3red-234x300.jpg 234w, https:\/\/static-blogs.laverdad.es\/wp-content\/uploads\/sites\/28\/2023\/01\/Yecla3red.jpg 413w\" sizes=\"(max-width: 234px) 100vw, 234px\" \/><\/a><\/p>\n<p><strong>Pero al final, todo apunta directo al coraz\u00f3n<\/strong><\/p>\n<p>La cuarta parada de este paseo es la b\u00fasqueda del coraz\u00f3n. Muchos no logran dar con \u00e9l. Se trata de una gran roca que, cual \u201cBocca della Verit\u00e0\u201d, tiene un orificio que semeja la forma de coraz\u00f3n. Todas las parejas en la excursi\u00f3n se hac\u00edan la foto en este rinc\u00f3n, pero ninguna se atrev\u00eda a meter la mano en \u00e9l.<\/p>\n<p>No es mala cosa -creo yo- comenzar las andaduras de este nuevo a\u00f1o, all\u00e1 \u201cdonde el coraz\u00f3n\u201d nos lleve; Puede ser un buen gu\u00eda acompa\u00f1ante \u00bfNo creen?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El primer mes del a\u00f1o viene con esta doble faz del dios Jano que a\u00fan mira al pasado, pero a la vez, puede girar hacia el futuro. Es lo todos conocemos como saber aprender del pasado para tomar sabias decisiones. Y al pasado que nos vamos, concretamente a aquellos remotos tiempos en los que [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13,18,39,61,65],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1644"}],"collection":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/comments?post=1644"}],"version-history":[{"count":4,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1644\/revisions"}],"predecessor-version":[{"id":1650,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/posts\/1644\/revisions\/1650"}],"wp:attachment":[{"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/media?parent=1644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/categories?post=1644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.laverdad.es\/zonadeembarque\/wp-json\/wp\/v2\/tags?post=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}